{"id":981136,"date":"2015-02-09T15:46:35","date_gmt":"2015-02-09T14:46:35","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=981136"},"modified":"2015-02-09T15:46:35","modified_gmt":"2015-02-09T14:46:35","slug":"sci-alpino-il-milanese-bosca-e-argento-nella-supercombinata","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2015\/02\/09\/sci-alpino-il-milanese-bosca-e-argento-nella-supercombinata\/","title":{"rendered":"SCI ALPINO: ALLE UNIVERSIADI IL MILANESE BOSCA E&#8217; ARGENTO NELLA SUPERCOMBINATA"},"content":{"rendered":"<p style=\"text-align: justify\">Dopo la medaglia d&#8217;oro di Michelangelo Tentori nel supergigante prosegue il &#8220;magic moment&#8221; lomnbardo alle Universiadi di sci alpino in corso di svolgimento in Spagna sulle nevi di Sierra Nevada.\u00a0 Nella prova di supercombinata di ieri il milanese del centro sportivo dell&#8217;Esercito, Giulio Bosca raccoglie una bellissima medaglia d&#8217;argento distanziato di soli 35 centesimi dallo svizzero Sandro Boner. I risultati degli altri azzurri in gara: quarto posto per Luca Riorda. 17esimo posto per il lecchese Pietro Migliazza con un gap di 3 secondi e 72 dal vincitore. Tentori, sci club Lecco, raccoglie la 22esima posizione. Out nella seconda manche: Alberto Chiappa.<\/p>\n<p style=\"text-align: justify\">In campo femminile Gaia Martinelli dello sci club Lecco raccoglie la nona piazza finale con un gap di 1 secondo e 52 dalla russa Daria Ovchinikova che ha vinto la gara.<\/p>\n<p style=\"text-align: justify\">Domani giornata di riposo. Si riprende mercoled\u00ec 11 febbraio con la prova di slalom gigante femminile. Il giorno seguente sar\u00e0 la volta di quello maschile. Il 13 ed il 14 febbraio, invece, spazio alla prova di slalom speciale femminile e maschile.<\/p>\n<p style=\"text-align: justify\">Marco Cerottini<br \/>\nUfficio stampa Comitato FISI Alpi Centrali<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo la medaglia d&#8217;oro di Michelangelo Tentori nel supergigante prosegue il &#8220;magic moment&#8221; lomnbardo alle Universiadi di sci alpino in corso di svolgimento in Spagna sulle nevi di Sierra Nevada.\u00a0 Nella prova di supercombinata di ieri il milanese del centro sportivo dell&#8217;Esercito, Giulio Bosca raccoglie una bellissima medaglia d&#8217;argento distanziato di soli 35 centesimi dallo svizzero Sandro Boner. I risultati&hellip;<\/p>\n","protected":false},"author":4,"featured_media":886744,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17,9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/981136"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=981136"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/981136\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/886744"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=981136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=981136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=981136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}