{"id":977302,"date":"2015-02-07T17:53:53","date_gmt":"2015-02-07T16:53:53","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=977302"},"modified":"2015-02-07T17:53:53","modified_gmt":"2015-02-07T16:53:53","slug":"biathlon-alpi-centrali-dargento-negli-italiani-a-staffetta","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2015\/02\/07\/biathlon-alpi-centrali-dargento-negli-italiani-a-staffetta\/","title":{"rendered":"BIATHLON: ALPI CENTRALI D&#8217;ARGENTO NEGLI ITALIANI A STAFFETTA"},"content":{"rendered":"<p style=\"text-align: justify\">Una stupenda giornata di sole ha fatto da perfetta cornice alla gara, che oggi ha assegnato il titolo italiano di staffetta. Sulla pista Lexert di Bionaz gli atleti dei vari comitati si sono sfidati per conquistare le medaglie in palio.\u00a0Nella categoria Junior\/Giovani femminile si laureano campionesse italiane Volgger Jasmine, Wiedenhofer Nathalie e Runggaldier Carmen del comitato Alto Adige. Vincono l&#8217;argento le Alpi Centrali con Zini Sara, Bormolini Camilla e Rainolter Ilaria. Bronzo per il Comitato Friuli Venezia Giulia con Del Fabbro Lucia, Quinz Luana e Fauner Eleonora.\u00a0Nella categoria Junior\/Giovani maschile \u00e8 il terzetto del Centro Sportivo Esercito a portare a casa l&#8217;oro con Guidetti Xavier, Majori Andrea e Zini Saverio. La medaglia d&#8217;argento va in Friuli Venezia Giulia con Fauner Filippo, Cappellari Daniele e Romanin Ivan. Conquista la medaglia di bronzo l&#8217;Asiva con Nicase Mattia, Jordaney Etienne e Di Francesco Federico.\u00a0Nella categoria Aspiranti femminile taglia per prima il traguardo Lardschneider Irene, conquistando cos\u00ec il titolo italiano per l&#8217;Alto Adige con le sue compagne di squadra Oberegger Anna Maria e Steinkasserer Simone. comitato Alto Adige si aggiudicano il titolo italiano precedendo le Alpi Occidentali con Vigna Martina, Ansaldi Annalisa e Boetti Laura. Il bronzo va all&#8217;Asiva con Cassol Martina, Borrettaz Irene e Comola Samuela.\u00a0Entusiasmante finale nella categoria Aspiranti dove Tumler Peter, Zingerle Georg e Braunhofer Patrick portano in Alto Adige il titolo italiano, precedendo l&#8217;Asiva con Gontel Kevin, Bianquin Matthieu e Christille Cedric e le Alpi Occidentali con Fissore Michele, Scaiola Xavier e Ponzo Manuel.\u00a0Domani alle ore 10 prender\u00e0 il via la gara sprint, valevole per la Coppa Italia Fiocchi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una stupenda giornata di sole ha fatto da perfetta cornice alla gara, che oggi ha assegnato il titolo italiano di staffetta. Sulla pista Lexert di Bionaz gli atleti dei vari comitati si sono sfidati per conquistare le medaglie in palio.\u00a0Nella categoria Junior\/Giovani femminile si laureano campionesse italiane Volgger Jasmine, Wiedenhofer Nathalie e Runggaldier Carmen del comitato Alto Adige. Vincono l&#8217;argento&hellip;<\/p>\n","protected":false},"author":4,"featured_media":886744,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17,9,10,12],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/977302"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=977302"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/977302\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/886744"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=977302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=977302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=977302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}