{"id":962207,"date":"2015-02-04T19:40:04","date_gmt":"2015-02-04T18:40:04","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=962207"},"modified":"2015-02-04T19:40:04","modified_gmt":"2015-02-04T18:40:04","slug":"indicative-allievi-gigante-e-slalom-1819-febbraio-le-nuove-date-del-recupero","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2015\/02\/04\/indicative-allievi-gigante-e-slalom-1819-febbraio-le-nuove-date-del-recupero\/","title":{"rendered":"Indicative Allievi Gigante e Slalom: 18\/19 Febbraio le nuove date del recupero"},"content":{"rendered":"<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">Verranno recuperate il prossimo <span style=\"color: #ff0000\"><strong>Mercoled\u00ec e Gioved\u00ec 18\/19 Febbraio<\/strong><\/span> sempre sulle piste di <strong><span style=\"color: #0000ff\">Val Palot e Montecampione<\/span><\/strong> le gare <span style=\"color: #ff0000\"><strong>Indicative Allievi Pen.100<\/strong><\/span> di <strong><span style=\"color: #0000ff\">Slalom <\/span><\/strong><span style=\"color: #000000\">e<\/span><strong><span style=\"color: #0000ff\"> Gigante<\/span><\/strong>. Le gare erano state rinviate lo scorso Gennaio a causa dell&#8217;inadeguato innevamento delle piste di gara.<\/p>\n<p style=\"text-align: justify\">Il nuovo programma sar\u00e0 il seguente, restando confermata la societ\u00e0 organizzatrice, lo <strong><span style=\"color: #0000ff\">Sci Club 90 Montecampione<\/span><\/strong>:<\/p>\n<table>\n<tbody>\n<tr>\n<td style=\"text-align: left\"><span style=\"color: #003300\"><strong>Mercoled\u00ec 18.02.15<\/strong><\/span><\/td>\n<td style=\"text-align: left\"><span style=\"color: #003300\"><strong>SL<\/strong><\/span><\/td>\n<td style=\"text-align: left\"><span style=\"color: #003300\"><strong>Val Palot<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left\"><span style=\"color: #003300\"><strong>Gioved\u00ec 19.02.15<\/strong><\/span><\/td>\n<td style=\"text-align: left\"><span style=\"color: #003300\"><strong>GS<\/strong><\/span><\/td>\n<td style=\"text-align: left\"><span style=\"color: #003300\"><strong>Montecampione<\/strong><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">Il programma dettagliato verr\u00e0 pubblicato appena disponibile nel calendario on-line in corrispondenza dei codici gara CA034\/035.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Verranno recuperate il prossimo Mercoled\u00ec e Gioved\u00ec 18\/19 Febbraio sempre sulle piste di Val Palot e Montecampione le gare Indicative Allievi Pen.100 di Slalom e Gigante. Le gare erano state rinviate lo scorso Gennaio a causa dell&#8217;inadeguato innevamento delle piste di gara. Il nuovo programma sar\u00e0 il seguente, restando confermata la societ\u00e0 organizzatrice, lo Sci Club 90 Montecampione: Mercoled\u00ec 18.02.15&hellip;<\/p>\n","protected":false},"author":4,"featured_media":962208,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15,16,22,32,26,24,33,27,25,34,28,29,20,31,21,17,30,9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/962207"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=962207"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/962207\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/962208"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=962207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=962207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=962207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}