{"id":924822,"date":"2015-01-31T18:02:15","date_gmt":"2015-01-31T17:02:15","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=924822"},"modified":"2015-01-31T18:02:15","modified_gmt":"2015-01-31T17:02:15","slug":"ski-alp-domani-a-livigno-il-circuito-alpi-centrali","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2015\/01\/31\/ski-alp-domani-a-livigno-il-circuito-alpi-centrali\/","title":{"rendered":"SKI ALP: DOMANI A LIVIGNO IL CIRCUITO ALPI CENTRALI"},"content":{"rendered":"<p style=\"text-align: justify\">Appuntamento domenica a Livigno con lo sci alpinismo giovanile ed il circuito di ski alp &#8220;Circuito Alpi Centrali&#8221; e riservato alle categorie Cadetti e Junior maschile e femminile. Si inizia alle 9.30 con la gara junior maschile. Percorso che presenta un dislivello positivo di 900 metri. 30 minuti pi\u00f9 tardi sar\u00e0 la volta delle altre categorie. Per loro dislivello positivo di 580 metri. Per tutti partenza e arrivo in prossimit\u00e0 di Plaza Placheda e Carosello 3000.<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">Marco Cerottini<br \/>\nUfficio stampa Comitato FISI Alpi Centrali<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Appuntamento domenica a Livigno con lo sci alpinismo giovanile ed il circuito di ski alp &#8220;Circuito Alpi Centrali&#8221; e riservato alle categorie Cadetti e Junior maschile e femminile. Si inizia alle 9.30 con la gara junior maschile. Percorso che presenta un dislivello positivo di 900 metri. 30 minuti pi\u00f9 tardi sar\u00e0 la volta delle altre categorie. Per loro dislivello positivo&hellip;<\/p>\n","protected":false},"author":4,"featured_media":886744,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17,9,10,18],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/924822"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=924822"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/924822\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/886744"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=924822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=924822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=924822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}