{"id":912094,"date":"2015-01-22T15:04:40","date_gmt":"2015-01-22T14:04:40","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=912094"},"modified":"2015-01-22T15:04:40","modified_gmt":"2015-01-22T14:04:40","slug":"sci-alpino-gigante-fis-junior-regionale-nel-segno-di-minazzi-e-confortola","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2015\/01\/22\/sci-alpino-gigante-fis-junior-regionale-nel-segno-di-minazzi-e-confortola\/","title":{"rendered":"SCI ALPINO: GIGANTE FIS JUNIOR REGIONALE NEL SEGNO DI MINAZZI E CONFORTOLA"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Ha preso avvio quest<img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-912103 \" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2015\/01\/SquadraMaschile.jpg\" alt=\"SquadraMaschile\" width=\"317\" height=\"254\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2015\/01\/SquadraMaschile.jpg 347w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2015\/01\/SquadraMaschile-300x240.jpg 300w\" sizes=\"(max-width: 317px) 100vw, 317px\" \/>&#8216;oggi a Santa Caterina una tre giorni di competizioni FIS Junior Regionale con una prova di slalom gigante, maschile e femminile.<\/p>\n<p>Nella gara degli \u201csci rosa\u201d prima piazza per Alessia Minazzi che ha concluso la sua performance con il crono di 2 primi 14 secondi e 48 rifilando 69 centesimi alla neo zelandese Eliza Grigg. Terza piazza (seconda miglior azzurra) per Jessica Torri che ha concluso la sua gara fra i pali larghi con 1 secondo e 68 di gap. La top five femminile vede al quarto posto la svizzera Fabia Unternaehrer con 1.72 dalla vincitrice e quinta piazza per Susanna Bernardini che ha concluso la sua performance con un gap di 2 secondi e 48 dalla vincitrice.<\/p>\n<p>Il \u201cpadrone di casa\u201d Matteo Confortola, che difende i colori dello Sci Club Santa Caterina si impone nella prova maschile sempre dei pali larghi. Dietro di lui Antonio Vittori (fresco di convocazione ai giochi Eyof 2015) con un gap di 10 centesimi dal valtellinese. Terza piazza per Matteo Rotunno dello Ski Racing Camp che ha accusato un gap di 66 centesimi dal vincitore. Nella top five di questa gara: quarta piazza per Pietro Zazzi con quasi 8 decimi di gap dal vincitore e Giacomo Rigamonti quinto con un distacco di 1 secondo e 45 centesimi. Per Rigamonti un rientro positivo dopo il grave infortunio della scorsa estate.<\/p>\n<p>Domani sempre a Santa Caterina si prosegue con un altra gara di slalom gigante valida per il circuito FIS Junior Regionale.<\/p>\n<p><a href=\"https:\/\/data.fis-ski.com\/dynamic\/results.html?sector=AL&amp;raceid=80351\" target=\"_blank\" rel=\"noopener\">Classifica Maschile<\/a><br \/>\n<a href=\"https:\/\/data.fis-ski.com\/dynamic\/results.html?sector=AL&amp;raceid=80352\" target=\"_blank\" rel=\"noopener\">Classifica Femminile<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Marco Cerottini<br \/>\nUfficio stampa Comitato FISI Alpi Centrali<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Ha preso avvio quest&#8216;oggi a Santa Caterina una tre giorni di competizioni FIS Junior Regionale con una prova di slalom gigante, maschile e femminile. Nella gara degli \u201csci rosa\u201d prima piazza per Alessia Minazzi che ha concluso la sua performance con il crono di 2 primi 14 secondi e 48 rifilando 69 centesimi alla neo zelandese Eliza Grigg. Terza&hellip;<\/p>\n","protected":false},"author":4,"featured_media":912098,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17,9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/912094"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=912094"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/912094\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/912098"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=912094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=912094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=912094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}