{"id":894148,"date":"2014-12-23T18:21:06","date_gmt":"2014-12-23T17:21:06","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=894148"},"modified":"2014-12-23T18:21:06","modified_gmt":"2014-12-23T17:21:06","slug":"sci-alpino-il-graffio-di-giulia-noris-al-gigante-walter-fontana","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2014\/12\/23\/sci-alpino-il-graffio-di-giulia-noris-al-gigante-walter-fontana\/","title":{"rendered":"SCI ALPINO: IL &#8220;GRAFFIO&#8221; DI GIULIA NORIS AL GIGANTE WALTER FONTANA"},"content":{"rendered":"<p style=\"text-align: justify\">Giulia Noris, dello sci club Ubi Banca Goggi, \u201cgraffia\u201d con una vittoria l&#8217;ultimo appuntamento di Chiesa Val Malenco con il 21esimo memorial Walter Fontana per il quale oggi si \u00e8 svolto uno slalom gigante. La Noris ha messo dietro la bellunese Sofia Pizzato e la valdostana Anna Damia<\/p>\n<p>In campo maschile al primo posto per il trentino Giulio Zuccarini. Al secondo posto il piemontese Nicolo Cerbo. Terza piazza per il veneto Pietro Canzio. Per quanto riguarda i colori del Comitato FISI Alpi Centrali nono posto per Federico Barzasi dello sci club Radici Group.<\/p>\n<p>Classifica femminile<br \/>\nhttps:\/\/data.fis-ski.com\/dynamic\/results.html?sector=AL&#038;raceid=80322<\/p>\n<p>Classifica maschile<br \/>\nhttps:\/\/data.fis-ski.com\/dynamic\/results.html?sector=AL&#038;raceid=82436<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">Marco Cerottini<br \/>\nUfficio stampa Comitato FISI Alpi Centrali<br \/>\nTel.: 3475791302<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Giulia Noris, dello sci club Ubi Banca Goggi, \u201cgraffia\u201d con una vittoria l&#8217;ultimo appuntamento di Chiesa Val Malenco con il 21esimo memorial Walter Fontana per il quale oggi si \u00e8 svolto uno slalom gigante. La Noris ha messo dietro la bellunese Sofia Pizzato e la valdostana Anna Damia In campo maschile al primo posto per il trentino Giulio Zuccarini. Al&hellip;<\/p>\n","protected":false},"author":4,"featured_media":891437,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17,9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/894148"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=894148"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/894148\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/891437"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=894148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=894148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=894148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}