{"id":891472,"date":"2014-12-13T16:12:29","date_gmt":"2014-12-13T15:12:29","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=891472"},"modified":"2014-12-13T16:12:29","modified_gmt":"2014-12-13T15:12:29","slug":"biathlon-comitato-fisi-alpi-centrali-a-valanga-in-val-martello","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2014\/12\/13\/biathlon-comitato-fisi-alpi-centrali-a-valanga-in-val-martello\/","title":{"rendered":"BIATHLON: COMITATO FISI ALPI CENTRALI A VALANGA IN VAL MARTELLO"},"content":{"rendered":"<p style=\"text-align: justify\">\u201cValanga\u201d di medaglie per gli atleti della squadra di biathlon del Comitato FISI Alpi Centrali quest\u2019oggi in Val Martello per la tappa del circuito di Coppa Italia.<\/p>\n<p style=\"text-align: justify\">Nella prova junior maschile prima piazza per Saverio Zini e quarto posto per Andrea Majori.<\/p>\n<p style=\"text-align: justify\">Nella prova giovani maschile ottimo secondo posto per Paolo Rodigari.<\/p>\n<p style=\"text-align: justify\">Ed ancora nella due medaglie di bronzo rispettivamente per Sara Zini nelle junior \u201crosa\u201d e per Camilla Bormolini fra le giovani.<\/p>\n<p style=\"text-align: justify\">Marco Cerottini<br \/>\nUfficio stampa Comitato FISI Alpi Centrali<br \/>\nTel.:3475791302<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cValanga\u201d di medaglie per gli atleti della squadra di biathlon del Comitato FISI Alpi Centrali quest\u2019oggi in Val Martello per la tappa del circuito di Coppa Italia. Nella prova junior maschile prima piazza per Saverio Zini e quarto posto per Andrea Majori. Nella prova giovani maschile ottimo secondo posto per Paolo Rodigari. Ed ancora nella due medaglie di bronzo rispettivamente&hellip;<\/p>\n","protected":false},"author":4,"featured_media":886744,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17,9,10,12],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/891472"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=891472"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/891472\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/886744"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=891472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=891472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=891472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}