{"id":891371,"date":"2014-12-01T14:17:30","date_gmt":"2014-12-01T13:17:30","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=891371"},"modified":"2014-12-01T14:17:30","modified_gmt":"2014-12-01T13:17:30","slug":"biathlon-good-luck-thomas-e-christian","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2014\/12\/01\/biathlon-good-luck-thomas-e-christian\/","title":{"rendered":"BIATHLON: GOOD LUCK THOMAS E CHRISTIAN"},"content":{"rendered":"<p style=\"text-align: justify\">Definita la squadra che prender\u00e0 parte alle prove individuali di biathlon di questa settimana in programma a Oestersund valida come prima tappa della Coppa del mondo. Fra gli azzurri un gradito ritorno \u201cgriffato\u201d Comitato FISI Alpi Centrali: Thomas Bormolini che dopo diverse difficolt\u00e0 dello scorso anno torna a difendere i colori azzurri. Il livignasco che corre per l&#8217;esercito \u00e8 \u201ccresciuto\u201d sportivamente parlando fra le fila dello sci club Alta Valtellina cos\u00ec come il bormino Christian De Lorenzi anche lui convocato per la trasferta svedese. Unitamente ai due atleti che hanno militato fra le fila della formazione lombarda di biathlon il direttore tecnico Fabrizio Curtaz ha convocato anche: Lukas Hofer, Dominik Windisch, ed ancora Dorothea Wierer, Karin Oberhofer, Nicole Gontier e Lisa Vittozzi fra le donne. Il programma: mercoled\u00ec 3 dicembre l&#8217;individuale maschile, seguita gioved\u00ec 4 dall&#8217;individuale femminile, sabato 6 dalle due sprint e domenica 7 dai due inseguimenti.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">Marco Cerottini<br \/>\nUfficio stampa Comitato FISI Alpi Centrali<br \/>\nTel.: 3475791302<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Definita la squadra che prender\u00e0 parte alle prove individuali di biathlon di questa settimana in programma a Oestersund valida come prima tappa della Coppa del mondo. Fra gli azzurri un gradito ritorno \u201cgriffato\u201d Comitato FISI Alpi Centrali: Thomas Bormolini che dopo diverse difficolt\u00e0 dello scorso anno torna a difendere i colori azzurri. Il livignasco che corre per l&#8217;esercito \u00e8 \u201ccresciuto\u201d&hellip;<\/p>\n","protected":false},"author":4,"featured_media":886744,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17,9,10,12],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/891371"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=891371"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/891371\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/886744"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=891371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=891371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=891371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}