{"id":891236,"date":"2014-11-26T14:00:06","date_gmt":"2014-11-26T13:00:06","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=891236"},"modified":"2014-11-26T14:00:06","modified_gmt":"2014-11-26T13:00:06","slug":"sci-alpinismo-murada-domenica-test-importante-in-vista-degli-italiani","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2014\/11\/26\/sci-alpinismo-murada-domenica-test-importante-in-vista-degli-italiani\/","title":{"rendered":"SCI ALPINISMO, MURADA: &#8220;DOMENICA TEST IMPORTANTE IN VISTA DEGLI ITALIANI&#8221;"},"content":{"rendered":"<p style=\"text-align: justify\">\u201cFuori i secondi\u201d, prendiamo in prestito questo motto pugilistico per parlare di sci alpinismo, perch\u00e9 <strong>questo fine settimana prende avvio la stagione 2014 \u2013 2015<\/strong> dello ski alp italiano. Sul ghiacciaio del Presana si terr\u00e0 infatti il primo fine settimana di competizioni in cui la formazione del <strong>Comitato FISI Alpi Centrali<\/strong> vuole essere subito protagonista.<\/p>\n<p>\u201cE&#8217; un test importante in cui potremmo fare un primo paragone con i nostri avversari\u201d il commento della vigilia di <strong>coach Ivan Murada<\/strong> che prosegue: \u201cla gara junior di domenica si svolger\u00e0 con la nuova formula a coppie e questo potrebbe essere anche un vantaggio per i nostri ragazzi. Eviteranno infatti lo stress di una competizione individuale ad inizio stagione. I ragazzi sono pronti e molto motivati per fare bene, anche se il nostro obiettivo \u00e8 quello legato ai campionati italiani di met\u00e0 dicembre in cui vogliamo vincere\u201d la conclusione di Murada.<\/p>\n<p><strong>Sabato 29 novembre<\/strong> \u00e8 n programma la gara<strong> Trofeo Crazy<\/strong> riservato alla categoria Senior mentre<strong> il giorno seguente<\/strong> sar\u00e0 la volta <strong>dell&#8217;Adamello Ski Raid Junior<\/strong> che assegner\u00e0 anche il 21esimo <strong>trofeo alla memoria di Fabio Stedile<\/strong>.<\/p>\n<p>Al via della competizione di domenica tutta la formazione del <strong>Comitato FISI Alpi Centrali<\/strong> di sci alpinismo al gran completo. Unitamente a coach Ivan Murada alla due giorni di competizioni ci sar\u00e0 anche l&#8217;altro tecnico del comitato lombardo: <strong>Adriano Greco<\/strong>.<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">Marco Cerottini<br \/>\nUfficio stampa Comitato FISI Alpi Centrali<br \/>\nTel.: 3475791302<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cFuori i secondi\u201d, prendiamo in prestito questo motto pugilistico per parlare di sci alpinismo, perch\u00e9 questo fine settimana prende avvio la stagione 2014 \u2013 2015 dello ski alp italiano. Sul ghiacciaio del Presana si terr\u00e0 infatti il primo fine settimana di competizioni in cui la formazione del Comitato FISI Alpi Centrali vuole essere subito protagonista. \u201cE&#8217; un test importante in&hellip;<\/p>\n","protected":false},"author":4,"featured_media":886744,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17,9,10,18],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/891236"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=891236"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/891236\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/886744"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=891236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=891236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=891236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}