{"id":891220,"date":"2014-11-24T15:46:08","date_gmt":"2014-11-24T14:46:08","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=891220"},"modified":"2014-11-24T15:46:08","modified_gmt":"2014-11-24T14:46:08","slug":"sci-alpino-le-squadre-del-comitato-al-lavoro-a-madesimo","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2014\/11\/24\/sci-alpino-le-squadre-del-comitato-al-lavoro-a-madesimo\/","title":{"rendered":"SCI ALPINO: LE SQUADRE DEL COMITATO AL LAVORO A MADESIMO"},"content":{"rendered":"<p style=\"text-align: justify\">Torna al lavoro la formazione maschile e femminile di sci alpino del <strong>Comitato FISI Alpi Centrali<\/strong> che, da domani 25 novembre, sar\u00e0 in allenamento sulle nevi di <strong>Madesimo<\/strong>.<\/p>\n<p style=\"text-align: justify\">Gli allenatori, <strong>Simone Stiletto e Elio Presazzi<\/strong>, hanno convocato 18 atleti, 7 maschi e 11 ragazze, per una quattro giorni di allenamenti dedicati in prevalenza a slalom speciale e gigante. Il collettivo di Madesimo si concluder\u00e0 il prossimo 28 novemnbre.<\/p>\n<p style=\"text-align: justify\">Qui di seguito l&#8217;elenco dei convocati da Stiletto e Presazzi<br \/>\nNicolas Bellini, Matteo Confortola, Marco Furli, Lorenzo Moschini, Giacomo Rigamonti, Alessio Scilligo e Antonio Vittori. In campo femminile ci saranno: Giulia Lorini, Martina Nobis, Giulia Noris, Veronica Olivieri, Petra Smaldore, Virginia Sosio ed ancora Chiara Cabello, Sara Ferrari, Carole Gilardoni, Marika Mascherona e Alessia Minazzi.<\/p>\n<p>Simone Stiletto e Elio Presazzi saranno coadiuvati da <strong>Maurilio Alessi<\/strong> e da <strong>Carlo Guattini<\/strong>.<\/p>\n<p style=\"text-align: justify\">Marco Cerottini<br \/>\nUfficio stampa Comitato FISI Alpi Centrali<br \/>\nTel.: 3475791302<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torna al lavoro la formazione maschile e femminile di sci alpino del Comitato FISI Alpi Centrali che, da domani 25 novembre, sar\u00e0 in allenamento sulle nevi di Madesimo. Gli allenatori, Simone Stiletto e Elio Presazzi, hanno convocato 18 atleti, 7 maschi e 11 ragazze, per una quattro giorni di allenamenti dedicati in prevalenza a slalom speciale e gigante. Il collettivo&hellip;<\/p>\n","protected":false},"author":4,"featured_media":890174,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17,9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/891220"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=891220"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/891220\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/890174"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=891220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=891220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=891220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}