{"id":890362,"date":"2014-10-28T14:40:31","date_gmt":"2014-10-28T13:40:31","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=890362"},"modified":"2014-10-28T14:40:31","modified_gmt":"2014-10-28T13:40:31","slug":"sci-alpino-bene-gli-atleti-del-comitato-alpi-centrali-nel-primo-gigante-di-stagione","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2014\/10\/28\/sci-alpino-bene-gli-atleti-del-comitato-alpi-centrali-nel-primo-gigante-di-stagione\/","title":{"rendered":"SCI ALPINO: BENE GLI ATLETI DEL COMITATO ALPI CENTRALI NEL PRIMO GIGANTE DI STAGIONE"},"content":{"rendered":"<p style=\"text-align: justify\"><a href=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/10\/stelvio271014.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-890359\" src=\"https:\/\/www.fisialpicentrali.it\/cms\/wp-content\/uploads\/2014\/10\/stelvio271014-300x150.jpg\" alt=\"stelvio271014\" width=\"300\" height=\"150\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/10\/stelvio271014-300x150.jpg 300w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/10\/stelvio271014.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Inizia nel migliore dei modi il primo appuntamento stagionale e per i colori dello scxi alpino del <strong>Comitato FISI Alpi Centrali<\/strong>. Nello slalom gigante, di ieri, andato in scena al <strong>Passo dello Stelvio<\/strong>, Filippo Beretta, del Circolo Sciatori di Madesimo, che raccoglie un primo ed un terzo posto nei due slalom giganti. Bene anche Luca Confortola dello Sci Club Altavaltellina. Da annotare anche il quarto posto di Thoams Rossi dell&#8217;Orezzo Val Seriana e quello di Federico Tomasoni che difende i colori dell&#8217;Ubi Banca Goggi. Degna di nota anche le performance di Alessadro Scuri, Circolo Sciatori Madesimo e di Alessio Scilligo dello sci club Formaza che raccolgono entrambi due decimi posti.<\/p>\n<p style=\"text-align: justify\">Notizie positive arrivano anche in campo femminile. Giulia Lorini, Circolo Sciatori Madesimo, centra due quarti posti. Giulia Noris, UBI Banca Goggi, centra un ottimo sesto posto. Da annotare anche il quinto posto di Debora Ferrari dello sci club Radici Group, il settimo posto per Jessica Totti, del Brixia, e l&#8217;ottavo posto per Romina Pozzi dello sci club Bormio.<\/p>\n<p style=\"text-align: justify\">Le competizioni sono dedicate a due \u201cpionieri\u201d dello sci lombardo: <strong>Dionigi e Rita Farina<\/strong>, valorosi atleti del\u00a0secondo dopoguerra.<\/p>\n<p style=\"text-align: justify\"><a title=\"Photogallery FIS_ENL Stelvio 27\/28.10.14\" href=\"https:\/\/www.fisialpicentrali.it\/cms\/sci-alpino\/galleria-fotografica-2\/nggallery\/sci-alpino\/sci-alpino-fis_enl-stelvio-2728-10-14\">Vai alla Photogallery<\/a><\/p>\n<p style=\"text-align: justify\">Marco Cerottini<br \/>\nUfficio stampa Comitato FISI Alpi Centrali<br \/>\nTel.: 3475791302<\/p>\n<p style=\"text-align: justify\"><a href=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/10\/stelvio271014c.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-890361\" src=\"https:\/\/www.fisialpicentrali.it\/cms\/wp-content\/uploads\/2014\/10\/stelvio271014c-300x150.jpg\" alt=\"stelvio271014c\" width=\"300\" height=\"150\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/10\/stelvio271014c-300x150.jpg 300w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/10\/stelvio271014c.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/10\/stelvio271014b.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-890360\" src=\"https:\/\/www.fisialpicentrali.it\/cms\/wp-content\/uploads\/2014\/10\/stelvio271014b-300x150.jpg\" alt=\"stelvio271014b\" width=\"300\" height=\"150\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/10\/stelvio271014b-300x150.jpg 300w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/10\/stelvio271014b.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inizia nel migliore dei modi il primo appuntamento stagionale e per i colori dello scxi alpino del Comitato FISI Alpi Centrali. Nello slalom gigante, di ieri, andato in scena al Passo dello Stelvio, Filippo Beretta, del Circolo Sciatori di Madesimo, che raccoglie un primo ed un terzo posto nei due slalom giganti. Bene anche Luca Confortola dello Sci Club Altavaltellina.&hellip;<\/p>\n","protected":false},"author":4,"featured_media":890358,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17,9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/890362"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=890362"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/890362\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/890358"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=890362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=890362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=890362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}