{"id":890295,"date":"2014-10-25T23:51:51","date_gmt":"2014-10-25T21:51:51","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=890295"},"modified":"2014-10-25T23:51:51","modified_gmt":"2014-10-25T21:51:51","slug":"secondo-sabato-dedicato-ai-direttori-di-gara","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2014\/10\/25\/secondo-sabato-dedicato-ai-direttori-di-gara\/","title":{"rendered":"Secondo Sabato dedicato ai Direttori di Gara"},"content":{"rendered":"<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-890296\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/10\/IMG_1514.jpg\" alt=\"Direttori di Gara 25.10.14\" width=\"357\" height=\"268\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/10\/IMG_1514.jpg 2272w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/10\/IMG_1514-300x225.jpg 300w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/10\/IMG_1514-1024x768.jpg 1024w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/10\/IMG_1514-768x576.jpg 768w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/10\/IMG_1514-1536x1152.jpg 1536w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/10\/IMG_1514-2048x1536.jpg 2048w\" sizes=\"(max-width: 357px) 100vw, 357px\" \/>Si \u00e8 tenuto oggi a Milano il secondo appuntamento dedicato ai Direttori di Gara di Sci Alpino. Quella di oggi \u00e8 stata una giornata piuttosto intesa, ben due gli appuntamenti dedicati ai Direttori di Gara, una figura alla quale il Comitato Alpi Centrali sta dedicando molta attenzione per l&#8217;importanza del ruolo che ricopre.<\/p>\n<p style=\"text-align: justify\">Nella mattinata oltre 40 i Direttori impegnati nell&#8217;aggiornamento, un incontro incentrato sul ripasso dei regolamenti e dei compiti principali di questa figura e sulle novit\u00e0 previste per la nuova stagione invernale. Nel pomeriggio invece si sono alternate altri 30 nuovi aspiranti DdG intenzionati ad inserire nell&#8217;Albo Regionale il loro nominativo per svolgere attivamente questo ruolo sul campo di gara in prima persona.<\/p>\n<p style=\"text-align: justify\">Al termine di questa seconda giornata Franco Zecchini, Presidente del Comitato e Docente di questi appuntamenti insieme a Marco Bocchiola, Consigliere Regionale e Responsabile Giudici, ha espresso tutta la sua soddisfazione per i 3 appuntamenti che si sono svolti a Milano nell&#8217;arco di 10 giorno, con una partecipazione che \u00e8 andata ben oltre le aspettative.<\/p>\n<p style=\"text-align: justify\">Il prossimo appuntamento \u00e8 fissato per Sabato 8 Novembre sempre a Milano, nell&#8217;occasione si svolgeranno gli esami per gli aspiranti direttori sia per il settore fondo che alpino. In bocca al lupo a tutti.<\/p>\n<p style=\"text-align: justify\"><a title=\"Photogallery DdG Ottobre 2014\" href=\"https:\/\/www.fisialpicentrali.it\/cms\/sci-alpino\/galleria-fotografica-2\/nggallery\/sci-alpino\/direttori-di-gara-ottobre-2014\"><em>Visita la Photogallery<\/em><\/a><\/p>\n<p style=\"text-align: right\">Marco Cerottini<br \/>\nUfficio stampa Comitato FISI Alpi Centrali<br \/>\nTel.:347.5791302<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si \u00e8 tenuto oggi a Milano il secondo appuntamento dedicato ai Direttori di Gara di Sci Alpino. Quella di oggi \u00e8 stata una giornata piuttosto intesa, ben due gli appuntamenti dedicati ai Direttori di Gara, una figura alla quale il Comitato Alpi Centrali sta dedicando molta attenzione per l&#8217;importanza del ruolo che ricopre. Nella mattinata oltre 40 i Direttori impegnati&hellip;<\/p>\n","protected":false},"author":4,"featured_media":890297,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15,30,9,10],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/890295"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=890295"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/890295\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/890297"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=890295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=890295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=890295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}