{"id":890265,"date":"2014-10-21T18:32:45","date_gmt":"2014-10-21T16:32:45","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=890265"},"modified":"2014-10-21T18:32:45","modified_gmt":"2014-10-21T16:32:45","slug":"sci-alpino-oggi-lavoro-fra-supergigante-e-gigante","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2014\/10\/21\/sci-alpino-oggi-lavoro-fra-supergigante-e-gigante\/","title":{"rendered":"SCI ALPINO: OGGI LAVORO FRA SUPERGIGANTE E GIGANTE"},"content":{"rendered":"<p style=\"text-align: justify\">Un&#8217;altra positiva giornata di allenamento \u00e8 andata in archivio per la formazione maschile e femminile dello sci alpino del <strong>Comitato FISI Alpi Centrali<\/strong> impegnate in un nuovo collettivo al Passo dello Stelvio. Complice un&#8217;altra bella giornata sono stati diversi i giri compiuti dalla formazione dell&#8217;alpino del comitato lombardo.<\/p>\n<p style=\"text-align: justify\">I ragazzi di coach <strong>Simone Stiletto<\/strong> si sono divisi quest&#8217;oggi: un gruppo ha fatto una sessione di slalom gigante e l&#8217;altra invece \u00e8 stata impegnata in supergigante.<\/p>\n<p style=\"text-align: justify\">La formazione femminile, invece, agli ordini di <strong>Elio Presazzi<\/strong> ha lavorato tutta insieme sulla velocit\u00e0 con positivi test in super gigante.<\/p>\n<p style=\"text-align: justify\">Domani, per il terzo giorno di allenamento di questo collettivo, giornata dedicata ai pali larghi con test di slalom gigante.<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">Marco Cerottini<br \/>\nUfficio stampa Comitato FISI Alpi Centrali<br \/>\nTel.: 3475791302<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un&#8217;altra positiva giornata di allenamento \u00e8 andata in archivio per la formazione maschile e femminile dello sci alpino del Comitato FISI Alpi Centrali impegnate in un nuovo collettivo al Passo dello Stelvio. Complice un&#8217;altra bella giornata sono stati diversi i giri compiuti dalla formazione dell&#8217;alpino del comitato lombardo. I ragazzi di coach Simone Stiletto si sono divisi quest&#8217;oggi: un gruppo&hellip;<\/p>\n","protected":false},"author":4,"featured_media":886744,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17,9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/890265"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=890265"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/890265\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/886744"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=890265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=890265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=890265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}