{"id":889110,"date":"2014-09-05T16:57:09","date_gmt":"2014-09-05T14:57:09","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=889110"},"modified":"2014-09-05T16:57:09","modified_gmt":"2014-09-05T14:57:09","slug":"sorio-e-gualazzi-sugli-scudi-oltre-equatore","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2014\/09\/05\/sorio-e-gualazzi-sugli-scudi-oltre-equatore\/","title":{"rendered":"SORIO E GUALAZZI SUGLI SCUDI OLTRE EQUATORE"},"content":{"rendered":"<p style=\"text-align: justify\"><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/2014\/09\/05\/sorio-e-gualazzi-sugli-scudi-oltre-equatore\/new_zeland\/\" rel=\"attachment wp-att-889106\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-889106\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/09\/new_zeland.jpg\" alt=\"new_zeland\" width=\"299\" height=\"171\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/09\/new_zeland.jpg 410w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/09\/new_zeland-300x172.jpg 300w\" sizes=\"(max-width: 299px) 100vw, 299px\" \/><\/a>Davvero una spedizione ricca di soddisfazione quella partita lo scorso 20 agosto da Milano Malpensa alla volta dell&#8217;Australia e Nuova Zelanda per i nostri due atleti, <strong>Daniele Sorio e Michele Gualazzi<\/strong> che stanno prendendo parte alle competizioni FIS a cavallo fra i due paesi dell&#8217;Oceania.<\/p>\n<p style=\"text-align: justify\">Andiamo per ordine. A fine agosto Daniele Sorio fra gigante e slalom raccoglie complessivamente due quinti posti ed una 17esima piazza, sulle montagne australiane di Mountain Hotman. Michele Gualazzi, invece, raccoglie nello slalom gigante un pi\u00f9 che onorevole settimo posto ed una dodicesima piazza.<br \/>\nSempre a fine agosto, ma sulle alture neo neozelandesi di Treble Cone, Daniele Sorio centra una bellissima vittoria nella prova di slalom gigante, mentre in speciale una pi\u00f9 che onorevole quinta piazza. Gualazzi out in slalom, nella prova fra i pali larghi raccoglie un quarto ed un quinto posto.<br \/>\nSi arriva cos\u00ec ad inizio settembre sui monti di Coronet Peak sempre in Nuova Zelanda. Ed ancora Daniele Sorio fa bella mostra di s\u00e9!. Centra infatti due secondi posti nello slalom gigante di mercoled\u00ec e gioved\u00ec, mentre Michele Gualazzi si piazza al decimo posto nel gigante del 3 settembre ed in 21esima posizione in quello di gioved\u00ec.<br \/>\nQuest&#8217;oggi, nella prova di slalom speciale, Sorio si piazza al 16esimo posto mentre Gualazzi in classifica \u00e8 giunto 24esimo.\u00a0 L\u2019ultimo appuntamento sulle nevi dell&#8217;Oceania sar\u00e0 quello di domani sabato 6 settembre con la gara di Slalom.<\/p>\n<p style=\"text-align: justify\">Unitamente ai due atleti lombardi oltre equatore c&#8217;\u00e8 anche l&#8217;allenatore<strong> Silvano Sorio<\/strong> e altri tre \u201catleti &#8211; compagni di avventura\u201d Pietro Franceschetti, Marco Manfrini e Nicol\u00f2 Menegalli.<\/p>\n<p style=\"text-align: justify\">Marco Cerottini<br \/>\nUfficio stampa del Comitato FISI Alpi Centrali<br \/>\nTel.:3475791302<\/p>\n<p style=\"text-align: justify\"><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/2014\/09\/05\/sorio-e-gualazzi-sugli-scudi-oltre-equatore\/new_zeland01\/\" rel=\"attachment wp-att-889108\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-889108\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/09\/new_zeland01.jpg\" alt=\"new_zeland01\" width=\"410\" height=\"235\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/09\/new_zeland01.jpg 410w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/09\/new_zeland01-300x172.jpg 300w\" sizes=\"(max-width: 410px) 100vw, 410px\" \/><\/a> <a href=\"https:\/\/www.fisialpicentrali.it\/cms\/2014\/09\/05\/sorio-e-gualazzi-sugli-scudi-oltre-equatore\/new_zeland02\/\" rel=\"attachment wp-att-889109\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-889109\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/09\/new_zeland02.jpg\" alt=\"new_zeland02\" width=\"410\" height=\"235\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/09\/new_zeland02.jpg 410w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/09\/new_zeland02-300x172.jpg 300w\" sizes=\"(max-width: 410px) 100vw, 410px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Davvero una spedizione ricca di soddisfazione quella partita lo scorso 20 agosto da Milano Malpensa alla volta dell&#8217;Australia e Nuova Zelanda per i nostri due atleti, Daniele Sorio e Michele Gualazzi che stanno prendendo parte alle competizioni FIS a cavallo fra i due paesi dell&#8217;Oceania. Andiamo per ordine. A fine agosto Daniele Sorio fra gigante e slalom raccoglie complessivamente due&hellip;<\/p>\n","protected":false},"author":4,"featured_media":889107,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17,9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/889110"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=889110"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/889110\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/889107"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=889110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=889110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=889110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}