{"id":886690,"date":"2014-06-30T15:08:42","date_gmt":"2014-06-30T13:08:42","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=886690"},"modified":"2014-06-30T15:08:42","modified_gmt":"2014-06-30T13:08:42","slug":"ski-roll-4-medaglie-per-i-colori-lombardi-a-orsago","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2014\/06\/30\/ski-roll-4-medaglie-per-i-colori-lombardi-a-orsago\/","title":{"rendered":"SKI ROLL: 4 MEDAGLIE PER I COLORI LOMBARDI A ORSAGO"},"content":{"rendered":"<p style=\"margin-bottom: 0cm;text-align: justify\" align=\"JUSTIFY\"><span style=\"font-size: large\">Ad Orsago si sono svolti i Campionati Italiani Sprint sulla lunghezza di 250 metri di ski roll, e dove hanno ben figurato gli atleti lombardi che al termine delle competizioni raccolgono <strong>ben 4 medaglie: 3 d&#8217;argento ed una di bronzo<\/strong>. \u00c8 mancato solo quella del metallo piu&#8217; prezioso per rendere perfetta questa giornata. Negli allievi femminile secondo posto per<strong> Giulia Cozzi<\/strong> dello sci club Bobbio. Da segnalare, sempre in questa categoria, anche il quinto posto per <strong>Iris Campana<\/strong> del Brianza Ski Roll Club. Nella prova maschile, altra medaglia d&#8217;argento grazie alla bella performance di <strong>Angelo Buttironi<\/strong> anche lui del Brianza Ski Roll Club. Nella top five anche <strong>Mattia Pasquali<\/strong> dello sci club Bobbio che raccoglie una piu&#8217; che onorevole quinta piazza. Nella prova assoluta femminile bel terzo posto per <strong>Nicole Bricalli<\/strong> della Polisportiva Valmalenco. Ai piedi del podio la brianzola <strong>Chiara Gelmi<\/strong>. Nella prova assoluta master da segnalare il sesto posto per <strong>Mattia Armellini<\/strong> dello sci lub Lissone. Infine il secondo posto per Italo Morandi dello sci club Bobbio.<\/span><\/p>\n<p style=\"margin-bottom: 0cm;text-align: justify\" align=\"JUSTIFY\">\n<p style=\"margin-bottom: 0cm;text-align: justify\" align=\"JUSTIFY\">\n<p style=\"margin-bottom: 0cm;text-align: justify\" align=\"JUSTIFY\">Marco Cerottini<br \/>\nUfficio stampa Comitato FISI Alpi Centrali<br \/>\nTel.: 3475791302<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ad Orsago si sono svolti i Campionati Italiani Sprint sulla lunghezza di 250 metri di ski roll, e dove hanno ben figurato gli atleti lombardi che al termine delle competizioni raccolgono ben 4 medaglie: 3 d&#8217;argento ed una di bronzo. \u00c8 mancato solo quella del metallo piu&#8217; prezioso per rendere perfetta questa giornata. Negli allievi femminile secondo posto per Giulia&hellip;<\/p>\n","protected":false},"author":4,"featured_media":881794,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17,9,10,12],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/886690"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=886690"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/886690\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/881794"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=886690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=886690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=886690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}