{"id":883867,"date":"2014-06-08T18:30:14","date_gmt":"2014-06-08T16:30:14","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=883867"},"modified":"2014-06-08T18:30:14","modified_gmt":"2014-06-08T16:30:14","slug":"sci-d-erba-sabato-lorenzo-gritti-domenica-fausto-cerentin-2","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2014\/06\/08\/sci-d-erba-sabato-lorenzo-gritti-domenica-fausto-cerentin-2\/","title":{"rendered":"Sci d&#8217; erba: sabato Lorenzo Gritti, domenica Fausto Cerentin!"},"content":{"rendered":"<p>Sabato<br \/>\nOggi si \u00e8 concluso il primo sprint slalom di coppa del mondo con la nostra Antonella Manzoni quinta, prima delle Italiane, e 21\u00b0 posto per il nostro Mattia.<br \/>\nDomani la seconda giornata di coppa del mondo sempre slalom speciale.<br \/>\nStrepitosa vittoria di Lorenzo Gritti nella prima gara stagionale valevole per la Coppa del mondo. Il 29enne bergamasco, promessa nella categoria juniores dove conquisto&#8217; tre medaglie d&#8217;oro iridate fra il 2004 e il 2005, ha vinto l&#8217;innovativo slalom sprint disputato sulla pista di Ravascletto. La formula della prova prevede la disputa di quattro manches a testa e le due migliori vanno a formare il tempo finale. Gritti ha concluso con 32&#8243;27&#8242;, seguito dal campione ceco Jan Nemec (32&#8243;27), terzo l&#8217;austriaco Michael Stocker con 32&#8243;33.<\/p>\n<p>L&#8217;ordine d&#8217;arrivo vede al quarto posto Fausto Cerentin, quinto Edoardo Frau, nono Andrea Notaris, dodicesimo Pietro Guerini, sedicesimo Matteo Battocchi, diciassettesimo Fabrizio Rottigni, diciannovesimo Nicholas Anziutti, ventunesimo Mattia Arrigoni, venticinquesimo Jacopo Facchin e ventiseiesimo Reghin.<\/p>\n<p>In campo femminile il successo e&#8217; andato alla ceca Adelaide Kettnerova (35&#8243;97) davanti alle austriache Kristin Hetflesich (36&#8243;40) e Lisa Vusits (36&#8243;42), quinta Antonella Manzoni e ottava Ilaria Sommavilla.<br \/>\nDomenica<\/p>\n<p>Dopo Lorenzo Gritti, ecco Fausto Cerentin,. E&#8217; ancora grande Italia nel primo weekend di Coppa del mondo disputato a Ravascletto. Se sabato era stato il bergamasco a imporsi nell&#8217;innovativa formula dello sprint slalom, la gara domenicale ha visto imporsi l&#8217;esperto veneto, classe 1973, il quale ha realizzato nelle due manches migliori (sulle quattro totali) il tempo di 33&#8243;28, precedendo il ceco Jan Nemec (per la seconda volta in due giorni al posto d&#8217;onore) di 9 centesimi, completa il podio l&#8217;austriaco Manuel Stocker a 11 centesimi. Gritti stavolta si \u00e8 piazzato sesto, seguito da Edoardo Frau ottavo, Andrea Notaris nono, Matteo Battocchi undicesimo, Fabrizio Rottigni quattordicesimo, Nichlas Anziutti diciannovesimo, Mattia Arrigoni ventunesimo, Jacopo Facchin ventitreesimo e Tommaso Reghin ventiseiesimo.<\/p>\n<p>Molto bene per la squadra azzurra sono andate le cose anche nella gara femminile, con Ilaria Sommavilla che ha concluso seconda a pari merito con l&#8217;austriaca Lisa Vusits con un ritard di 24 centesimi dalla ceca Adela Kettnerova che ha concluso col tempo di 37&#8243;16. Nell&#8217;ordine d&#8217;arrivo figura anche Antonella Manzoni ottava, ritirata Elisabetta Polvara.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sabato Oggi si \u00e8 concluso il primo sprint slalom di coppa del mondo con la nostra Antonella Manzoni quinta, prima delle Italiane, e 21\u00b0 posto per il nostro Mattia. Domani la seconda giornata di coppa del mondo sempre slalom speciale. Strepitosa vittoria di Lorenzo Gritti nella prima gara stagionale valevole per la Coppa del mondo. Il 29enne bergamasco, promessa nella&hellip;<\/p>\n","protected":false},"author":4,"featured_media":883868,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,19],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/883867"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=883867"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/883867\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/883868"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=883867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=883867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=883867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}