{"id":883622,"date":"2014-04-18T23:19:19","date_gmt":"2014-04-18T21:19:19","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=883622"},"modified":"2014-04-18T23:19:19","modified_gmt":"2014-04-18T21:19:19","slug":"adamello-ski-si-scia-fino-al-2-giugno","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2014\/04\/18\/adamello-ski-si-scia-fino-al-2-giugno\/","title":{"rendered":"Adamello Ski: Si scia fino al 2 giugno"},"content":{"rendered":"<p>Si scia ancora al Passo Tonale e sul ghiacciaio Presena ma la stagione sciistica volge ormai al termine e molte piste chiuderanno tra marted\u00ec 22 e mercoled\u00ec 23 aprile.\u00a0<\/p>\n<p>In particolare:<br \/>-Dal 22 aprile saranno chiuse le seggiovie Alpe Alta, Vittoria e Presanella ed il Tubbo.<br \/>&#8211; Dal 23 aprile saranno chiuse le seggiovie Nigritella, Bleis, Valbiolo, Contrabbandieri e Tonale Occidentale.<br \/>&#8211; Dal 23 al 27 aprile saranno in funzione gli impianti 3 Larici, Serodine e Valena e la cabinovia Pontedilegno-Tonale.<\/p>\n<p>La pista Paradiso rimarr\u00e0 aperta fino al 1 maggio.\u00a0<\/p>\n<p>Noi per\u00f2 gli sci li toglieremo pi\u00f9 avanti: il 1 maggio prender\u00e0 il via lo sci primaverile sul ghiacciaio Presena e ce lo vogliamo godere fino al 2 giugno!\u00a0<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si scia ancora al Passo Tonale e sul ghiacciaio Presena ma la stagione sciistica volge ormai al termine e molte piste chiuderanno tra marted\u00ec 22 e mercoled\u00ec 23 aprile.\u00a0 In particolare:-Dal 22 aprile saranno chiuse le seggiovie Alpe Alta, Vittoria e Presanella ed il Tubbo.&#8211; Dal 23 aprile saranno chiuse le seggiovie Nigritella, Bleis, Valbiolo, Contrabbandieri e Tonale Occidentale.&#8211; Dal&hellip;<\/p>\n","protected":false},"author":4,"featured_media":883623,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[22,9],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/883622"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=883622"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/883622\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/883623"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=883622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=883622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=883622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}