{"id":880248,"date":"2014-04-05T16:37:21","date_gmt":"2014-04-05T14:37:21","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=880248"},"modified":"2014-04-05T16:37:21","modified_gmt":"2014-04-05T14:37:21","slug":"542014-madesimo-fis-junior-regionale-tutti-i-risultati-dello-slalom","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2014\/04\/05\/542014-madesimo-fis-junior-regionale-tutti-i-risultati-dello-slalom\/","title":{"rendered":"5\/4\/2014  &#8211; MADESIMO FIS JUNIOR REGIONALE TUTTI I RISULTATI DELLO SLALOM"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Primo appuntamento della\u00a0due giorni dedicati alla sci alpino sulla pista Italo Pedroncelli di Medesimo\u00a0che ospitata le\u00a0FIS Junior Regionali, organizzate dal\u00a0Circolo Sciatori di Medesimo. Oggi l\u2019appuntamento con lo slalom speciale.<\/p>\n<p>&nbsp;<\/p>\n<p>In campo maschile si impone\u00a0Matteo Baruffaldi\u00a0che difende i colori dell\u2019ASD Caspoggio che si \u00e8 imposto con il crono di 1\u201936.48 rifilando 16 centesimo aLorenzo Moschini\u00a0del Collio. Terza piazza per il bergamasco \u201ctargato\u201d Radici Group\u00a0Nicola Ottelli.<\/p>\n<p>&nbsp;<\/p>\n<p>La prova \u201crosa\u201d \u00e8 stata vinta dalla bergamasca\u00a0Roberta Melesi\u00a0\u201cgriffata\u201d Sci Club Radici Group. La Melesi ha concluso la sua performance con il crono di 1\u201941.25. Al secondo posto la livignisca\u00a0Jole Galli. Chiude il podio un&#8217;altra atleta del Radici Group: Sola Ymer.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Marco Cerottini<\/p>\n<p>Ufficio stampa Comitato FISI Alpi Centrali<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Primo appuntamento della\u00a0due giorni dedicati alla sci alpino sulla pista Italo Pedroncelli di Medesimo\u00a0che ospitata le\u00a0FIS Junior Regionali, organizzate dal\u00a0Circolo Sciatori di Medesimo. Oggi l\u2019appuntamento con lo slalom speciale. &nbsp; In campo maschile si impone\u00a0Matteo Baruffaldi\u00a0che difende i colori dell\u2019ASD Caspoggio che si \u00e8 imposto con il crono di 1\u201936.48 rifilando 16 centesimo aLorenzo Moschini\u00a0del Collio. Terza piazza per&hellip;<\/p>\n","protected":false},"author":4,"featured_media":829457,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/880248"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=880248"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/880248\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/829457"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=880248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=880248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=880248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}