{"id":880217,"date":"2014-04-03T14:00:30","date_gmt":"2014-04-03T12:00:30","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=880217"},"modified":"2014-04-03T14:00:30","modified_gmt":"2014-04-03T12:00:30","slug":"elezioni-federali-bologna-1242014","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2014\/04\/03\/elezioni-federali-bologna-1242014\/","title":{"rendered":"Elezioni Federali &#8211; PIETRO MAROCCO: \u201cRISCONTRI POSITIVI IN TUTTA ITALIA, NESSUNA ALLEANZA CON  MANUELA DI CENTA\u201d"},"content":{"rendered":"<p>Da Udine a Genova, passando per Biella e nelle prossime ore per Aosta e\u00a0<br \/>Torino. E&#8217; un tour de force decisamente favorevole quello a cui si sta\u00a0<br \/>sottoponendo Pietro Marocco, attuale presidente del Comitato FISI Alpi\u00a0<br \/>Occidentali e candidato al ruolo di Presidente nazionale della FISI: \u00abOvunque\u00a0<br \/>abbiamo avuto riscontri positivi, sto constatando che si mandano segnali\u00a0<br \/>precisi al territorio e soprattutto alla base, questa ha ancora l&#8217;entusiasmo\u00a0<br \/>sir rispondere, c&#8217;\u00e8 grande volont\u00e0 di partecipazione. Purtroppo in questi\u00a0<br \/>ultimi anni i dirigenti della FISI spesso non sono stati capaci di cogliere\u00a0<br \/>queste richieste, mentre gli stimoli che arrivano dai tesserati sono notevoli e\u00a0<br \/>l&#8217;abbiamo visto ovunque siamo stati in questi giorni, anche a Biella\u00bb. La\u00a0<br \/>Liguria ufficialmente non si \u00e8 ancora \u00a0schierata, ma l&#8217;idea sembra chiara: \u00abCi\u00a0<br \/>sono moltissime convergenze tra le loro esigenze e le idee che porto avanti con\u00a0<br \/>il mio programma\u00bb. Invece nessun accordo con l&#8217;altra candidata. Manuela Di<br \/>Centa, come qualcuno ha ipotizzato negli ultimi giorni: \u00abC&#8217;\u00e8 un sano e\u00a0<br \/>rispettoso confronto, come si conviene a persone civili. Ma abbiamo progetti e\u00a0<br \/>programmi diversi e ognuno andr\u00e0 avanti per la sua strada, io credo\u00a0<br \/>profondamente in quello che propongo per rilanciare la FISI\u00bb.<br \/>Uno dei punti caldi nella gestione della FISI sar\u00e0 come e dove reperire le\u00a0<br \/>risorse. Anche in questo caso Pietro Marocco ha idee chiarissime: \u00abE\u2019 indubbio\u00a0<br \/>che, negli ultimi anni, le entrate della Federazione hanno subito una cospicua\u00a0<br \/>diminuzione mentre le spese, soprattutto per quanto riguarda i costi di\u00a0<br \/>funzionamento, sono aumentate. La razionalizzazione della spesa pu\u00f2 contribuire\u00a0<br \/>a migliorare i conti, ma non basta: la realt\u00e0 \u00e8 che bisogna aumentare le\u00a0<br \/>entrate. Occorre bussare a tutte le porte, cercare risorse aggiuntive,\u00a0<br \/>migliorare la qualit\u00e0 e il numero delle sponsorizzazioni, valorizzare il brand\u00a0<br \/>FISI, agire sul merchandising, valutare quanto sar\u00e0 ottenibile dai diritti\u00a0<br \/>televisivi e quali e quante risorse aggiuntive saranno ottenibili dal CONI e\u00a0<br \/>dalla eventuale partecipazione a bandi nazionali ed europei a sostegno della\u00a0<br \/>pratica sportiva\u00bb.\u00a0<br \/>Ecco quindi le prime possibili mosse: \u00abSe sar\u00f2 eletto Presidente verificher\u00f2\u00a0<br \/>con attenzione quanto previsto dal recente contratto sottoscritto dal\u00a0<br \/>Presidente Roda con la Infront, una societ\u00e0 (lo voglio precisare a scanso di\u00a0<br \/>equivoci) che ha indubbiamente una forte vocazione ed una notevole esperienza\u00a0<br \/>nel mondo della neve e con la quale potremo collaborare proficuamente. Solo la\u00a0<br \/>trasparenza dei conti pu\u00f2 rendere la Federazione un soggetto nuovamente capace\u00a0<br \/>di attrarre nuovi ingenti investimenti in sponsorizzazioni\u00bb.<\/p>\n<p>I PROSSIMI INCONTRI SUL TERRITORIO DEL CANDIDATO PIETRO MAROCCO\u00a0<br \/>&#8211; gioved\u00ec\u00a0\u00a0 03\/04\u00a0\u00a0\u00a0ore 18 ad Aosta: incontro con gli Sci Club del Comitato\u00a0<br \/>valdostano FISI\u00a0ASIVA\u00a0<br \/>&#8211;\u00a0<a href=\"\/\/1\">venerd\u00ec \u00a004\/04<\/a>\u00a0\u00a0\u00a0\u00a0ore 21 a Torino: incontro con gli Sci Club piemontesi,\u00a0<br \/>presso Circolo Ronchi Verdi, corso Moncalieri 466\/16<br \/>&#8211; sabato05\/04\u00a0 \u00a0\u00a0ore 18 a Bolzano: incontro con gli Sci Club del Comitato FISI\u00a0<br \/>Alto Adige<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da Udine a Genova, passando per Biella e nelle prossime ore per Aosta e\u00a0Torino. E&#8217; un tour de force decisamente favorevole quello a cui si sta\u00a0sottoponendo Pietro Marocco, attuale presidente del Comitato FISI Alpi\u00a0Occidentali e candidato al ruolo di Presidente nazionale della FISI: \u00abOvunque\u00a0abbiamo avuto riscontri positivi, sto constatando che si mandano segnali\u00a0precisi al territorio e soprattutto alla base, questa&hellip;<\/p>\n","protected":false},"author":4,"featured_media":871042,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15,9],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/880217"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=880217"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/880217\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/871042"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=880217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=880217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=880217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}