{"id":879851,"date":"2014-03-29T17:12:44","date_gmt":"2014-03-29T16:12:44","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=879851"},"modified":"2014-03-29T17:12:44","modified_gmt":"2014-03-29T16:12:44","slug":"2932014-abetone-si-e-aperto-il-pinocchio-sugli-sci-2014","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2014\/03\/29\/2932014-abetone-si-e-aperto-il-pinocchio-sugli-sci-2014\/","title":{"rendered":"29\/3\/2014 &#8211;  ABETONE: SI E\u2019 APERTO IL PINOCCHIO SUGLI SCI 2014"},"content":{"rendered":"<p>La pista \u201cZeno Col\u00f2\u201d ha ospitato questa mattina la prima gara dell\u2019edizione2014 del Pinocchio sugli sci. Al via la categoria baby con la prova di slalom gigante e, subito, arriva la prima medaglia per i colori del\u00a0Comitato FISI Alpi Centrali.<\/p>\n<p>&nbsp;<\/p>\n<p>Nella prova maschile, infatti, il bergamasco \u201cgriffato\u201d\u00a0Sci Club Radici Group Lorenzo Gerosa\u00a0raccoglie una bellissima\u00a0medaglia d\u2019argento\u00a0nella prova vinta dal bellunese Vittorio De Pieri. Completa il podio la terza piazza del piemontese Pietro Ambrosone.<\/p>\n<p>&nbsp;<\/p>\n<p>Nella prova femminile la medaglia d\u2019oro va ad un&#8217;altra piemontese: Matilde Casse dello sci club San Sicario. Dietro di lei Ilaria Sabatino dell\u2019ASD Eur e terzo posto per Emma Parisotto dello sci club Montebelluna. Nei primi dieci anche la\u00a0bresciana dello sci club Valpalot Giulia Romele. Ed ancora degna di nota la prova di\u00a0Rebecca Melis dello sci club Santa Caterina\u00a0che raccoglie la undicesima posizione.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/wp-content\/uploads\/2014\/03\/1682_Classifica-ufficialeBaby1pinocchioabetone2.pdf\" target=\"_blank\" rel=\"noopener\">Classifica\u00a0<\/a><\/p>\n<p>Marco Cerottini<\/p>\n<p>Ufficio stampa Comitato FISI Alpi Centrali<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pista \u201cZeno Col\u00f2\u201d ha ospitato questa mattina la prima gara dell\u2019edizione2014 del Pinocchio sugli sci. Al via la categoria baby con la prova di slalom gigante e, subito, arriva la prima medaglia per i colori del\u00a0Comitato FISI Alpi Centrali. &nbsp; Nella prova maschile, infatti, il bergamasco \u201cgriffato\u201d\u00a0Sci Club Radici Group Lorenzo Gerosa\u00a0raccoglie una bellissima\u00a0medaglia d\u2019argento\u00a0nella prova vinta dal bellunese&hellip;<\/p>\n","protected":false},"author":4,"featured_media":879856,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/879851"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=879851"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/879851\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/879856"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=879851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=879851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=879851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}