{"id":879830,"date":"2014-03-29T14:59:26","date_gmt":"2014-03-29T13:59:26","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=879830"},"modified":"2014-03-29T14:59:26","modified_gmt":"2014-03-29T13:59:26","slug":"2732014-pietro-marocco-in-alpi-centrali-attenzione-massima-alla-base","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2014\/03\/29\/2732014-pietro-marocco-in-alpi-centrali-attenzione-massima-alla-base\/","title":{"rendered":"27\/3\/2014 &#8211; PIETRO MAROCCO IN ALPI CENTRALI: \u201cATTENZIONE MASSIMA ALLA BASE\u201d &#8211; VIDEO &#8211;"},"content":{"rendered":"<p><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/2014\/03\/27\/2732014-pietro-marocco-in-alpi-centrali-attenzione-massima-alla-base\/conferenza-marocco7\/\" rel=\"attachment wp-att-879862\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-879862\" alt=\"Conferenza Marocco7\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/03\/Conferenza-Marocco7.jpg\" width=\"591\" height=\"394\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/03\/Conferenza-Marocco7.jpg 591w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/03\/Conferenza-Marocco7-300x200.jpg 300w\" sizes=\"(max-width: 591px) 100vw, 591px\" \/><\/a><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/2014\/03\/27\/2732014-pietro-marocco-in-alpi-centrali-attenzione-massima-alla-base\/conferenza-marocco8\/\" rel=\"attachment wp-att-879863\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-879863\" alt=\"Conferenza Marocco8\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/03\/Conferenza-Marocco8.jpg\" width=\"591\" height=\"394\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/03\/Conferenza-Marocco8.jpg 591w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/03\/Conferenza-Marocco8-300x200.jpg 300w\" sizes=\"(max-width: 591px) 100vw, 591px\" \/><\/a><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/2014\/03\/27\/2732014-pietro-marocco-in-alpi-centrali-attenzione-massima-alla-base\/conferenza-marocco2\/\" rel=\"attachment wp-att-879864\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-879864\" alt=\"Conferenza Marocco2\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/03\/Conferenza-Marocco2.jpg\" width=\"591\" height=\"394\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/03\/Conferenza-Marocco2.jpg 591w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/03\/Conferenza-Marocco2-300x200.jpg 300w\" sizes=\"(max-width: 591px) 100vw, 591px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/2014\/03\/27\/2732014-pietro-marocco-in-alpi-centrali-attenzione-massima-alla-base\/conferenza-marocco\/\" rel=\"attachment wp-att-879866\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-879866\" alt=\"Conferenza Marocco\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/03\/Conferenza-Marocco.jpg\" width=\"591\" height=\"394\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/03\/Conferenza-Marocco.jpg 591w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/03\/Conferenza-Marocco-300x200.jpg 300w\" sizes=\"(max-width: 591px) 100vw, 591px\" \/><\/a><\/p>\n<p>Uomini e donne che animano il \u201cpopolo\u201d della Federazione Italiana Sport Invernali, sono stati al centro dell&#8217;incontro di mercoled\u00ec sera alla sede delComitato FISI Alpi Centrali, da parte di\u00a0Pietro Marocco, l&#8217;ingegnere piemontese che ha presentato la propria candidatura alla presidenza della Federazione Italiana Sport Invernali.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cNon c&#8217;\u00e8 altezza senza base \u2013 afferma il candidato\u00a0Pietro Marocco\u00a0\u2013 perch\u00e9la base,\u00a0ovvero gli sci club ed i comitati regionali sono\u00a0l&#8217;elemento chiave della mia proposta: la FISI non deve essere solo d&#8217;aiuto da un punto di vista economico per gli sci club,\u00a0ecco perch\u00e9 ho proposto che parte dei finanziamenti erogati dal CONI siano distribuiti in modo equo sul territorio. Ma oltre al sostegno, economico, la FISI\u00a0deve\u00a0anche\u00a0fornire una serie di consulenza sulla gestione dei sodalizi\u00a0perch\u00e9 essere presidente di uno sci club\u00a0oggi\u00a0\u00e8 molto difficile. Ecco perch\u00e9 la Federazione deve essere vicina a questi uomini e queste donne offrendo, per esempio, degli sportelli a loro dedicati per affrontare i problemi di ogni giorno.\u00a0Inoltre ritengo indispensabile il confronto con il territorio, con le realt\u00e0 che lavorano quasi quotidianamente sul campo\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Ampio il dibattito fra i rappresentati degli sci club e dei comitati\u00a0provinciali\u00a0che sono intervenuti: dal tema del tesseramento a quello della ricerca. \u201cE proprio sulla ricerca, mi riallaccio ancora una volta alla base \u2013\u00a0afferma\u00a0Marocco\u00a0-occorre investire in questo ambito per garantire la crescita e per consentirci di stare al passo coi tempi, magari attraverso il coinvolgimento dei privati e dei vari strumenti che vengono offerti dall&#8217;Unione Europea. Altro tema fondamentale \u2013 ha proseguito\u00a0Marocco\u00a0\u2013 quello \u00e8 quello legato al tesseramento. In questi ultimi anni abbiamo assistito ad un calo del numero di\u00a0tesserati.\u00a0Occorre invertire questo trend perch\u00e9 \u00e8 frutto di disaffezione verso la Federazione. Oggi i tesserati, sono gli atleti i loro allenatori, i dirigenti ed i\u00a0genitori che sottoscrivono la tessera, presso la sci club di appartenenza del proprio figlio. Cos\u00ec per\u00f2 perdiamo di vista una massa enorme di\u00a0affezionati.Ecco perch\u00e9 occorre invertire questo trend \u2013\u00a0ha concluso\u00a0Pietro Marocco\u00a0-attraverso soluzioni\u00a0che sono gi\u00e0 in essere in altre realt\u00e0 sportive, o propendo soluzioni di tesseramento pi\u00f9 semplici.\u201d<\/p>\n<div>\n<div>\u00a0<\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p>Marco Cerottini<\/p>\n<p>Ufficio stampa Comitato FISI Alpi Centrali<\/p>\n<p>&nbsp;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uomini e donne che animano il \u201cpopolo\u201d della Federazione Italiana Sport Invernali, sono stati al centro dell&#8217;incontro di mercoled\u00ec sera alla sede delComitato FISI Alpi Centrali, da parte di\u00a0Pietro Marocco, l&#8217;ingegnere piemontese che ha presentato la propria candidatura alla presidenza della Federazione Italiana Sport Invernali. &nbsp; \u201cNon c&#8217;\u00e8 altezza senza base \u2013 afferma il candidato\u00a0Pietro Marocco\u00a0\u2013 perch\u00e9la base,\u00a0ovvero gli sci&hellip;<\/p>\n","protected":false},"author":4,"featured_media":879862,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15,9,10],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/879830"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=879830"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/879830\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/879862"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=879830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=879830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=879830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}