{"id":862113,"date":"2014-03-06T16:06:46","date_gmt":"2014-03-06T15:06:46","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=862113"},"modified":"2014-03-06T16:06:46","modified_gmt":"2014-03-06T15:06:46","slug":"632014-campo-felice-giornata-da-dimenticare-nello-speciale-femminile-cancellato-il-gigante-maschile","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2014\/03\/06\/632014-campo-felice-giornata-da-dimenticare-nello-speciale-femminile-cancellato-il-gigante-maschile\/","title":{"rendered":"6\/3\/2014 &#8211; CAMPO FELICE: GIORNATA DA DIMENTICARE NELLO SPECIALE FEMMINILE CANCELLATO IL GIGANTE MASCHILE"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Giornata difficile, meteorologicamente parlando, per i\u00a0campionati italiani aspiranti\u00a0di\u00a0Campo Felice. Nella localit\u00e0 abruzzese per l&#8217;intera giornata ha insistito la nebbia che ha costretto gli organizzatori ad\u00a0annullare la seconda manche dello slalom gigante maschile, ultimo atto di questa intensa due giorni tricolore. La partenza della seconda frazione era stata dapprima rinviata e successivamente, dopo la discesa di soli 4 atleti \u00e8 stata sospesa. Visto il perdurare della nebbia \u00e8 stato deciso di cancellare la gara.<\/p>\n<p>&nbsp;<\/p>\n<p>Al termine della prima frazione di gara, fra i pali larghi, brillavano i colori delComitato FISI Alpi Centrali. Il miglior tempo era di\u00a0Lorenzo Moschini\u00a0con 57\u201d49 seguito dal compagno di squadra\u00a0Antonio Vittori\u00a0che ha chiuso la prima frazione di gara con il crono di 57\u201d80. La terza piazza provvisoria era occupata dal piemontese Alberto Blengini che ha chiuso la sua performance con il crono di 58\u201d01.<\/p>\n<p>&nbsp;<\/p>\n<p>Si \u00e8 svolto, invece, regolarmente lo\u00a0slalom speciale femminile. Ad imporsi \u00e8 stata Sara Dellantonio del Trentino. Dietro di lei la valdostana Elisa Formari e terza piazza per un altra trentina: Laura Pirovano.\u00a0Out\u00a0nella prima mancheVirginia Sosio, mentre nella seconda frazione \u00e8 uscita\u00a0Roberta Melesi. Miglior atleta della formazione allenata da Elio Presazzi \u00e8 stata\u00a0Carole Gilardoni\u00a0dello sci club\u00a0Ubi Banca Goggi\u00a0che centra la\u00a022esima\u00a0posizione. Nelle trenta anche\u00a0Giulia Della Moneta\u00a0del\u00a0GB Ski Club.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>.<\/p>\n<p>Marco Cerottini<\/p>\n<p>Ufficio stampa Comitato FISI Alpi Centrali<\/p>\n<p>Tel.:\u00a0<a href=\"tel:3475791302\">3475791302<\/a><a name=\"_PictureBullets\"><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Giornata difficile, meteorologicamente parlando, per i\u00a0campionati italiani aspiranti\u00a0di\u00a0Campo Felice. Nella localit\u00e0 abruzzese per l&#8217;intera giornata ha insistito la nebbia che ha costretto gli organizzatori ad\u00a0annullare la seconda manche dello slalom gigante maschile, ultimo atto di questa intensa due giorni tricolore. La partenza della seconda frazione era stata dapprima rinviata e successivamente, dopo la discesa di soli 4 atleti \u00e8&hellip;<\/p>\n","protected":false},"author":4,"featured_media":862114,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/862113"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=862113"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/862113\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/862114"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=862113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=862113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=862113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}