{"id":841709,"date":"2014-03-01T16:36:52","date_gmt":"2014-03-01T15:36:52","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=841709"},"modified":"2014-03-01T16:36:52","modified_gmt":"2014-03-01T15:36:52","slug":"132013-bormio-oggi-lo-slalom-gigante-regionale-allievi-e-le-prove-del-supergigante-ragazzi","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2014\/03\/01\/132013-bormio-oggi-lo-slalom-gigante-regionale-allievi-e-le-prove-del-supergigante-ragazzi\/","title":{"rendered":"1\/3\/2013 BORMIO: OGGI LO SLALOM GIGANTE REGIONALE ALLIEVI E LE PROVE DEL SUPERGIGANTE RAGAZZI -VIDEO &#8211;"},"content":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<a href=\"https:\/\/www.fisialpicentrali.it\/cms\/2014\/03\/01\/132013-bormio-oggi-lo-slalom-gigante-regionale-allievi-e-le-prove-del-supergigante-ragazzi\/image-292\/\" rel=\"attachment wp-att-842399\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-842399\" alt=\"image\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/03\/image4.jpg\" width=\"600\" height=\"448\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/03\/image4.jpg 600w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/03\/image4-300x224.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p align=\"CENTER\">\u00a0<a href=\"https:\/\/www.fisialpicentrali.it\/cms\/2014\/03\/01\/132013-bormio-oggi-lo-slalom-gigante-regionale-allievi-e-le-prove-del-supergigante-ragazzi\/image-290\/\" rel=\"attachment wp-att-842397\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-842397\" alt=\"image\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/03\/image2.jpg\" width=\"600\" height=\"448\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/03\/image2.jpg 600w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/03\/image2-300x224.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a>\u00a0<\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">Nonostante un cielo nuvoloso si \u00e8 svolto regolarmente lo <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>slalom gigante<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Allievi, maschile e femminile<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">, valido per l\u2019assegnazione del <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>titolo regionale<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"> per la categoria e primo atto della quattro giorni di competizioni promosse dallo <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Sci Club Bormio<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"> che ospiter\u00e0 sino a marted\u00ec le massime competizioni dello sci alpino del <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Comitato FISI Alpi Centrali<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"> per la categoria Allievi e per la categoria Ragazzi.<\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">Nella prova \u201crosa\u201d trionfo della bergamasca \u201cgriffata\u201d<\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b> Sci Club Radici Giulia Borsatti<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"> che centra la medaglia d\u2019oro facendo fermare il crono sul tempo di 1:32.15. Dietro di lei a sei decimi <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Silvia Turla<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"> dello <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Ski Team Valpalot<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">. Terza piazza per <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Giulia Ghislandi<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"> dello <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>sci club Lecco<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">.<\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">Nella prova maschile altro successo per lo <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>sci club Radici<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"> con <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Federico Barzasi<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"> che si laurea neo campione regionale di specialit\u00e0 nella sua categoria con il tempo di 1:25:96. Dietro di lui il padrone di casa <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>dello sci club Bormio Fabiano Canclini <\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">che ha concluso con il tempo di 1:26.24. Medaglia di bronzo per <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Andrea Modanesi dello sci club Collio<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">.<\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">In scena quest\u2019oggi anche la prova cronometrata del <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>supergigante Ragazzi<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">. <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Domani <\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">il programma prevede: la gara di super gigante per la categoria Ragazzi sulla pista \u201cStelvio\u201d e lo slalom speciale per la categoria Allievi.<\/span><\/span><\/p>\n<p align=\"JUSTIFY\">\u00a0<\/p>\n<p style=\"text-align: left\" align=\"RIGHT\"><span style=\"font-family: Arial, sans-serif\">Marco Cerottini<br \/><\/span><span style=\"font-family: Arial, sans-serif\">Ufficio stampa Comitato FISI Alpi Centrali<br \/><\/span><span style=\"font-family: Arial, sans-serif\">Tel.:3475791302<\/span><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 Nonostante un cielo nuvoloso si \u00e8 svolto regolarmente lo slalom giganteAllievi, maschile e femminile, valido per l\u2019assegnazione del titolo regionale per la categoria e primo atto della quattro giorni di competizioni promosse dallo Sci Club Bormio che ospiter\u00e0 sino a marted\u00ec le massime competizioni dello&hellip;<\/p>\n","protected":false},"author":4,"featured_media":842401,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/841709"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=841709"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/841709\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/842401"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=841709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=841709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=841709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}