{"id":838455,"date":"2014-02-25T23:08:33","date_gmt":"2014-02-25T22:08:33","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=838455"},"modified":"2014-02-25T23:08:33","modified_gmt":"2014-02-25T22:08:33","slug":"sci-alpino-indicative-slalom-categoria-ragazzi-monte-pora","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2014\/02\/25\/sci-alpino-indicative-slalom-categoria-ragazzi-monte-pora\/","title":{"rendered":"25\/2\/2014 &#8211; Sci Alpino &#8211; Indicative Slalom Categoria Ragazzi Monte Pora"},"content":{"rendered":"<p>Si sono svolte oggi \u00a0al Monte Pora le gare indicative per la categoria ragazzi \u00a0e la due giorni \u00e8 iniziata con lo slalom.<\/p>\n<p>Tra le ragazze il miglior tempo e&#8217; stato staccato da Ilaria Ghisalberti dello sci club Radici, seconda Valentina Vecchi dello sci club Lecco e terza Sofia Furli dello sci club Bormio.<\/p>\n<p>Sul gradino piu alto del podio maschile e&#8217; salito Giacomo Bertini dello sci clubBrixia seguito da Nicola Moretti dello Ski Team Val Palot e da Giovanni Alex Zino dello sci club Livigno.<\/p>\n<p>Seguiranno ulteriori dettagli<\/p>\n<p>&nbsp;<\/p>\n<p><a title=\"indicative ragazzi\" href=\"https:\/\/www.fisialpicentrali.it\/cms\/wp-content\/uploads\/2014\/02\/CLS_002253_classifica-finaleindrag.pdf\" target=\"_blank\" rel=\"noopener\">Classifiche<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si sono svolte oggi \u00a0al Monte Pora le gare indicative per la categoria ragazzi \u00a0e la due giorni \u00e8 iniziata con lo slalom. Tra le ragazze il miglior tempo e&#8217; stato staccato da Ilaria Ghisalberti dello sci club Radici, seconda Valentina Vecchi dello sci club Lecco e terza Sofia Furli dello sci club Bormio. Sul gradino piu alto del podio&hellip;<\/p>\n","protected":false},"author":4,"featured_media":838457,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16,9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/838455"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=838455"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/838455\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/838457"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=838455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=838455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=838455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}