{"id":821264,"date":"2014-02-13T16:26:47","date_gmt":"2014-02-13T15:26:47","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=821264"},"modified":"2014-02-13T16:26:47","modified_gmt":"2014-02-13T15:26:47","slug":"1322014-temu-prove-cronometrate-indicative-categorie-allievi-domani-la-gara","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2014\/02\/13\/1322014-temu-prove-cronometrate-indicative-categorie-allievi-domani-la-gara\/","title":{"rendered":"13\/2\/2014 &#8211;  TEMU&#8217;: PROVE CRONOMETRATE INDICATIVE CATEGORIE ALLIEVI, DOMANI LA GARA"},"content":{"rendered":"<p>Sono iniziate oggi le prove\u00a0indicative di super gigante riservati alla categoria Allievi\u00a0sulle nevi di Tem\u00f9 che ha accolto gli sciatori con una bella giornata di sole, trasformatasi poi in pioggia che comunque non ha deteriorato la pista.<\/p>\n<p>&nbsp;<\/p>\n<p>La gara, vera e propria \u00e8 in programma\u00a0domani, venerd\u00ec 14 febbraio, ed \u00e8 organizzata dallo sci club 90 Montecampione. \u00a0<\/p>\n<p>&nbsp;<\/p>\n<p>Le prove di oggi, cos\u00ec come la gara di domani si svolger\u00e0 sulla\u00a0pista Santa Giulia, che cambia il programma originario che avrebbe dovuto essere la pista Serodine al Passo del Tonale. Una decisione assunta dagli organizzatori a causa dell&#8217;abbondante innevamento.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Marco Cerottini<\/p>\n<p>Ufficio stampa Comitato FISI Alpi Centrali<\/p>\n<p>Tel.:\u00a0<a href=\"tel:3475791302\">3475791302<\/a><a name=\"_PictureBullets\"><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sono iniziate oggi le prove\u00a0indicative di super gigante riservati alla categoria Allievi\u00a0sulle nevi di Tem\u00f9 che ha accolto gli sciatori con una bella giornata di sole, trasformatasi poi in pioggia che comunque non ha deteriorato la pista. &nbsp; La gara, vera e propria \u00e8 in programma\u00a0domani, venerd\u00ec 14 febbraio, ed \u00e8 organizzata dallo sci club 90 Montecampione. \u00a0 &nbsp; Le&hellip;<\/p>\n","protected":false},"author":4,"featured_media":821265,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/821264"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=821264"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/821264\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/821265"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=821264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=821264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=821264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}