{"id":809138,"date":"2014-02-06T21:55:38","date_gmt":"2014-02-06T20:55:38","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=809138"},"modified":"2014-02-06T21:55:38","modified_gmt":"2014-02-06T20:55:38","slug":"alberto-chiappa-campione-del-mondo-cittadini-in-slalom-gigante-terzo-nicolo-colombi","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2014\/02\/06\/alberto-chiappa-campione-del-mondo-cittadini-in-slalom-gigante-terzo-nicolo-colombi\/","title":{"rendered":"6\/2\/2014 &#8211; ALBERTO CHIAPPA  CAMPIONE DEL MONDO CITTADINI IN SLALOM GIGANTE  TERZO NICOLO COLOMBI"},"content":{"rendered":"<p align=\"CENTER\">\u00a0<\/p>\n<p align=\"JUSTIFY\"><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/2014\/02\/06\/alberto-chiappa-campione-del-mondo-cittadini-in-slalom-gigante-terzo-nicolo-colombi\/alberto-sport-sci-erna-chiappaart\/\" rel=\"attachment wp-att-809143\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-809143\" alt=\"Alberto-Sport-sci-erna-Chiappaart\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/02\/Alberto-Sport-sci-erna-Chiappaart.jpg\" width=\"600\" height=\"345\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/02\/Alberto-Sport-sci-erna-Chiappaart.jpg 600w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/02\/Alberto-Sport-sci-erna-Chiappaart-300x173.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a>\u00a0<\/p>\n<p align=\"JUSTIFY\">Nella foto da lecconotizie.com : Alberto Chiappa &#8212;-<\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Arial, sans-serif\"><span>Una giornata storica per per i colori del<\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span><b> Comitato FISI Alpi Centrali<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span>. L\u2019alfiere dello <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span><b>sci club Erna, Alberto Chiappa<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span> classe 1992, si \u00e8 laureato oggi <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span><b>campione del mondo in slalom gigante<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span> per la <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span><b>categoria FIS Cittadini<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span> sulle nevi transalpine di <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span><b>Les Menuires<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span>.<\/span><\/span><\/p>\n<p align=\"JUSTIFY\">U<span style=\"font-family: Arial, sans-serif\">na performance perfetta quella del lecchese con due manche senza sbavature. Chiappa ha concluso la prima manche in testa e non ha pi\u00f9 lasciato la posizione di leader assoluto facendo segnare in entrambe le due manche con il miglior tempo assoluto.<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Arial, sans-serif\">Al secondo posto nella classifica assoluta, \u00e8 salito l\u2019inglese Nicholas Moynihan (1994) ed il francese Hugo Salerno (1995). Ai piedi del podio, ma <\/span><span style=\"font-family: Arial, sans-serif\"><b>medaglia di bronzo<\/b><\/span><span style=\"font-family: Arial, sans-serif\"> per quanto riguarda la classifica del Criterium FIS Cittadini un altro esponente del <\/span><span style=\"font-family: Arial, sans-serif\"><b>Comitato FISI Alpi Centrali: Nicol\u00f2 Colombi<\/b><\/span><span style=\"font-family: Arial, sans-serif\">, classe 1991, che difende i colori dello <\/span><span style=\"font-family: Arial, sans-serif\"><b>sci club Goggi.<\/b><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Arial, sans-serif;color: #000000;line-height: 1.5em\">Le due medaglie sono certamente per i due nostri atleti Alberto e Nicol\u00f2\u00a0\u00a0un importante stimolo e una riprova che i sacrifici e l&#8217;allenamento alla fine vengono ripagati.<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000\"><span style=\"font-family: Arial, sans-serif\"><span>Nella localit\u00e0 francese, e precisamente a Val Thorens ad inizio settimana, luned\u00ec e marted\u00ec, sono stati assegnati i titoli Mondiali Cittadini per le prove veloci, Discesa e SuperG. Al cancelletto di partenza anche un altro nostro atleta, <\/span><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Arial, sans-serif\"><span><b>Stefano Zucchi<\/b><\/span><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Arial, sans-serif\"><span> (1994) tesserato con lo <\/span><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Arial, sans-serif\"><span><b>Sci Club Rongai<\/b><\/span><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Arial, sans-serif\"><span>. Non avendo la qualifica cittadino, non ha potuto concorrere all\u2019assegnazione del titolo, ma \u00e8 pi\u00f9 che giusto ricordare le sue performance in entrambe le gare che l\u2019hanno visto infatti conquistare la terza posizione assoluta in Discesa e la seconda in SuperG.<\/span><\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000\"><span style=\"font-family: Arial, sans-serif\"><span>Domani appuntamento con l\u2019ultima medaglia in palio, quella in Slalom.<\/span><\/span><\/span><\/p>\n<p style=\"text-align: left\" align=\"RIGHT\"><span style=\"font-family: Arial, sans-serif\">Marco Cerottini<br \/><\/span><span style=\"font-family: Arial, sans-serif\">Ufficio stampa Comitato FISI Alpi Centrali<br \/><\/span><span style=\"font-family: Arial, sans-serif\">Tel.:3475791302<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Nella foto da lecconotizie.com : Alberto Chiappa &#8212;- Una giornata storica per per i colori del Comitato FISI Alpi Centrali. L\u2019alfiere dello sci club Erna, Alberto Chiappa classe 1992, si \u00e8 laureato oggi campione del mondo in slalom gigante per la categoria FIS Cittadini sulle nevi transalpine di Les Menuires. Una performance perfetta quella del lecchese con due&hellip;<\/p>\n","protected":false},"author":4,"featured_media":809139,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[24,9,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/809138"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=809138"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/809138\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/809139"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=809138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=809138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=809138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}