{"id":801465,"date":"2014-02-03T14:24:03","date_gmt":"2014-02-03T13:24:03","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=801465"},"modified":"2014-02-03T14:24:03","modified_gmt":"2014-02-03T13:24:03","slug":"322014-pozza-di-fassa-ecco-i-convocati-per-le-prove-di-confronto-delle-5-nazionali","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2014\/02\/03\/322014-pozza-di-fassa-ecco-i-convocati-per-le-prove-di-confronto-delle-5-nazionali\/","title":{"rendered":"3\/2\/2014 &#8211; POZZA DI FASSA: ECCO I CONVOCATI PER LE PROVE DI CONFRONTO DELLE 5 NAZIONALI"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>La\u00a0Federazione Italiana Sport Invernali\u00a0ha selezionato\u00a0gli\u00a0atleti che il prossimo\u00a05 e 6 febbraio\u00a0prenderanno parte alla manifestazione\u00a05 Nazionaliin programma a\u00a0Pozza di Fassa.<\/p>\n<p>&nbsp;<\/p>\n<p>In tutto sono\u00a05\u00a0i ragazzi dello sci alpino \u201ctaragati\u201d\u00a0Comitato FISI Alpi Centraliche prenderanno parte a questa\u00a0prestigiosa\u00a0manifestazione, e selezionati dalla FISI stessa. Rispetto al contingente originario la\u00a0Commissione giovaniha autorizzato, per\u00f2, alcune modifiche in seguito agli infortuni che hanno coinvolto Angelica Rizzi e Maddalena Agnelli, convocate in un primo momento. Al loro posto scenderanno in pista\u00a0Romina Pozzi\u00a0(SC Bormio) eGiulia Ghislandi\u00a0dello\u00a0SC Lecco. Confermati gli altri tre atleti selezionati.Marika Mascherona\u00a0dello\u00a0SC Bormio, e due atleti dello\u00a0sci club Lecco:Davide Baruffaldi\u00a0e\u00a0Nicol\u00f2 Molteni.<\/p>\n<p>&nbsp;<\/p>\n<p>Il programma della manifestazione, prevede:\u00a0mercoled\u00ec 5 febbraio\u00a0una giornata di allenamento al mattino. Sempre mercoled\u00ec\u00a0prima manche per loslalom ispeciale n nottuna\u00a0che scatter\u00e0 alle 17. La seconda frazione invece, scatter\u00e0 30 minuti dopo il termina della prima manche. Il giorno seguente,\u00a0gioved\u00ec 6 febbraio, sar\u00e0 di scena lo\u00a0slalom gigante. Il via della competizione alle 9.30. La seconda frazione, cos\u00ec come per la prova fra i pali snodati, scatter\u00e0 30 minuti dopo il termine della prima manche.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Marco Cerottini<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; La\u00a0Federazione Italiana Sport Invernali\u00a0ha selezionato\u00a0gli\u00a0atleti che il prossimo\u00a05 e 6 febbraio\u00a0prenderanno parte alla manifestazione\u00a05 Nazionaliin programma a\u00a0Pozza di Fassa. &nbsp; In tutto sono\u00a05\u00a0i ragazzi dello sci alpino \u201ctaragati\u201d\u00a0Comitato FISI Alpi Centraliche prenderanno parte a questa\u00a0prestigiosa\u00a0manifestazione, e selezionati dalla FISI stessa. Rispetto al contingente originario la\u00a0Commissione giovaniha autorizzato, per\u00f2, alcune modifiche in seguito agli infortuni che hanno coinvolto Angelica Rizzi&hellip;<\/p>\n","protected":false},"author":4,"featured_media":801466,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/801465"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=801465"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/801465\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/801466"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=801465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=801465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=801465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}