{"id":552777,"date":"2014-01-23T17:39:03","date_gmt":"2014-01-23T16:39:03","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=552777"},"modified":"2014-01-23T17:39:03","modified_gmt":"2014-01-23T16:39:03","slug":"2312014-monte-pora-oggi-la-prima-prova-di-indicative-allievi-vicono-la-borsatti-e-talacci","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2014\/01\/23\/2312014-monte-pora-oggi-la-prima-prova-di-indicative-allievi-vicono-la-borsatti-e-talacci\/","title":{"rendered":"23\/1\/2014 &#8211; MONTE PORA: OGGI LA PRIMA PROVA DI INDICATIVE ALLIEVI VICONO LA BORSATTI E TALACCI &#8211; VIDEO &#8211;"},"content":{"rendered":"<p><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/2014\/01\/23\/2312014-monte-pora-oggi-la-prima-prova-di-indicative-allievi-vicono-la-borsatti-e-talacci\/borsatti-giulia-1-class-ac\/\" rel=\"attachment wp-att-552783\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-552783\" alt=\"Borsatti Giulia 1^ class ac\" src=\"https:\/\/www.fisialpicentrali.it\/cms\/wp-content\/uploads\/2014\/01\/Borsatti-Giulia-1^-class-ac.jpg\" width=\"600\" height=\"400\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/01\/Borsatti-Giulia-1^-class-ac.jpg 600w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/01\/Borsatti-Giulia-1^-class-ac-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a>\u00a0<\/p>\n<p>\u00a0<a href=\"https:\/\/www.fisialpicentrali.it\/cms\/2014\/01\/23\/2312014-monte-pora-oggi-la-prima-prova-di-indicative-allievi-vicono-la-borsatti-e-talacci\/talacci-martin-ac\/\" rel=\"attachment wp-att-552781\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-552781\" alt=\"Talacci Martin ac\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/01\/Talacci-Martin-ac.jpg\" width=\"600\" height=\"400\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/01\/Talacci-Martin-ac.jpg 600w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/01\/Talacci-Martin-ac-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Prima giornata di gare a\u00a0Monte Pora,\u00a0sulla pista Coppa Europa Fausto Radici\u00a0per le prove\u00a0indicative di slalom gigante\u00a0aperti alla categoria\u00a0Allievi maschile e femminile. La due giorni \u00e8 valida per la qualificazione ai campionati italiani di categoria e per il Trofeo Topolino. La qualificazione alle prove nazionali terr\u00e0 conto dei risultati delle due gare in programma, che sono organizzate dallo\u00a0Sci Club Radici Group.<\/p>\n<p>&nbsp;<\/p>\n<p>Nella prova \u201crosa\u201d prima piazza per\u00a0la padrona di casa\u00a0Giulia Borsatti\u00a0che difende i colori dello sci club Radici Group.\u00a0Al secondo posto\u00a0Marika Mascherona\u00a0dello sci club Bormio\u00a0e al terzo Ilaria Tognoli\u00a0anche lei targata SC Radici Group.. La prova maschile, invece, \u00e8 stata vinta da\u00a0Martin Talaccidello sci club Ligino.\u00a0Al secondo posto\u00a0Davide Baruffaldi\u00a0dello sci club Leccoe terzo posto per\u00a0Christian Balduzzi\u00a0dello sci club 13 Clusone.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Domani altro appuntamento con le prove indicative. In programma la gara dislalom speciale. La due giorni di competizioni assegner\u00e0 anche il nono trofeo alla memoria di Gianni Radici.<\/p>\n<p>&nbsp;<\/p>\n<p>Marco Cerottini<\/p>\n<p>Fisi Alpi Centrali\u00a0<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Prima giornata di gare a\u00a0Monte Pora,\u00a0sulla pista Coppa Europa Fausto Radici\u00a0per le prove\u00a0indicative di slalom gigante\u00a0aperti alla categoria\u00a0Allievi maschile e femminile. La due giorni \u00e8 valida per la qualificazione ai campionati italiani di categoria e per il Trofeo Topolino. La qualificazione alle prove nazionali terr\u00e0 conto dei risultati delle due gare in programma, che sono organizzate dallo\u00a0Sci Club&hellip;<\/p>\n","protected":false},"author":4,"featured_media":552785,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16,9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/552777"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=552777"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/552777\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/552785"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=552777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=552777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=552777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}