{"id":552081,"date":"2014-01-19T20:41:33","date_gmt":"2014-01-19T19:41:33","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=552081"},"modified":"2014-01-19T20:41:33","modified_gmt":"2014-01-19T19:41:33","slug":"1912014-alpi-centrali-comitato-campione-nazionale-giovani","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2014\/01\/19\/1912014-alpi-centrali-comitato-campione-nazionale-giovani\/","title":{"rendered":"19\/1\/2014 &#8211;  ALPI CENTRALI COMITATO CAMPIONE NAZIONALE GIOVANI"},"content":{"rendered":"<p><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/2014\/01\/19\/1912014-alpi-centrali-comitato-campione-nazionale-giovani\/ci-med-bronzo\/\" rel=\"attachment wp-att-552084\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-552084\" alt=\"ci med bronzo\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/01\/ci-med-bronzo.jpg\" width=\"600\" height=\"298\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/01\/ci-med-bronzo.jpg 600w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2014\/01\/ci-med-bronzo-300x149.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Nella foto: Simone Romani Elisa Carrara e Nicola Fornoni \u00a0 \u00a0&#8212;\u00a0<\/p>\n<p>A\u00a0Forni di Sopra, nonostante una giornata dominata dalla avverse condizioni meteo, il\u00a0Comitato FISI Alpi Centrali\u00a0si laurea\u00a0campione italiano giovani\u00a0di sci nordico. Grazie ad una magistrale prova corale di tutti gli atleti il\u00a0Comitato FISI Alpi Centrali\u00a0supera in classifica il Trentino ed il comitato dell\u2019Alto Adige.<\/p>\n<p>&nbsp;<\/p>\n<p>Oggi, ultima giornata di gara per i campionati nazionali giovani ed ancora una prova magistrale di tutti gli atleti che sono stati impegnati nella gara individuale.<\/p>\n<p>&nbsp;<\/p>\n<p>Nella categoria aspiranti femminile medaglia di\u00a0bronzo per Elisa Carraradello\u00a0sci club 13 Clusone\u00a0a soli 7 decimi dalla seconda classificata. Nella stessa categoria sesto posto per\u00a0Chiara Busi\u00a0dello\u00a0sci club Prima Luna, settimo posto per\u00a0Chiara Zini\u00a0del\u00a0Livigno\u00a0e nono posto per\u00a0Laura Gusminidello\u00a0sci club Gromo. In campo maschile altro\u00a0bronzo\u00a0per i colori delComitato FISI Alpi Centrali\u00a0con\u00a0Nicola Fornoni\u00a0dello\u00a0sci club 13 Clusone. Dietro di lui, al quarto posto,\u00a0Davide Bonacorsi\u00a0del\u00a0Gromo\u00a0ed ancora sesto posto per\u00a0Adriano Giudici\u00a0dello\u00a0sci club Schilpario. Nella stessa categoria da segnalare anche l\u2019ottimo ottavo posto per\u00a0Luca Speroni\u00a0del\u00a0Cunardo\u00a0e l\u2019undicesima piazza per\u00a0Luca Agoni\u00a0dello\u00a0SC Schilpario.<\/p>\n<p>&nbsp;<\/p>\n<p>Nella prova junior maschile arriva un altro\u00a0bronzo\u00a0con\u00a0Simone Romani\u00a0dellosci club Alta Valtellina. Nella stessa categoria da segnalare il buon quinto posto per\u00a0Manuel Perotti, anche lui\u00a0SC Alta Valtellina, ed ancora l\u2019ottavo posto per\u00a0Claudio Venosta\u00a0della\u00a0Polisportiva Le Prese\u00a0ed il decimo posto per\u00a0Cristian Morelli\u00a0dello\u00a0SC Schilpario. In campo femminile, invece, buon sesto posto per la valtellinese\u00a0Alice Canclini. Nei dieci anche la compagna di club Beatrice Rocca.<\/p>\n<p>Marco Cerottini<\/p>\n<p>Ufficio stampa Comitato FISI Alpi Centrali<\/p>\n<p>Tel.:<a href=\"tel:3475791302\">3475791302<\/a><\/p>\n<p>Comitato Regionale Alpi Centrali Via G.B. Piranesi 46 \u2013 Milano<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nella foto: Simone Romani Elisa Carrara e Nicola Fornoni \u00a0 \u00a0&#8212;\u00a0 A\u00a0Forni di Sopra, nonostante una giornata dominata dalla avverse condizioni meteo, il\u00a0Comitato FISI Alpi Centrali\u00a0si laurea\u00a0campione italiano giovani\u00a0di sci nordico. Grazie ad una magistrale prova corale di tutti gli atleti il\u00a0Comitato FISI Alpi Centrali\u00a0supera in classifica il Trentino ed il comitato dell\u2019Alto Adige. &nbsp; Oggi, ultima giornata di gara&hellip;<\/p>\n","protected":false},"author":4,"featured_media":552084,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,12],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/552081"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=552081"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/552081\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/552084"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=552081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=552081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=552081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}