{"id":543583,"date":"2013-12-12T21:15:10","date_gmt":"2013-12-12T20:15:10","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=543583"},"modified":"2013-12-12T21:15:10","modified_gmt":"2013-12-12T20:15:10","slug":"12122013-paganella-cosi-nello-slalom-gigante-di-coppa-europa-nicole-agnelli-e-terza","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2013\/12\/12\/12122013-paganella-cosi-nello-slalom-gigante-di-coppa-europa-nicole-agnelli-e-terza\/","title":{"rendered":"12\/12\/2013 &#8211; PAGANELLA: COSI&#8217; NELLO SLALOM GIGANTE DI COPPA EUROPA NICOLE AGNELLI E&#8217; TERZA!"},"content":{"rendered":"<p><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/23112013-sci-alpino-coppa-europa-femminile-ancora-una-bella-gara-di-nicole-agnelli\/nicol-agnelli2\/\" rel=\"attachment wp-att-543279\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-543279\" alt=\"Nicol Agnelli2\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/11\/Nicol-Agnelli2.jpg\" width=\"200\" height=\"300\" \/><\/a><\/p>\n<p>\u00a0Nella foto Nicole Agnelli &#8212; \u00a0<\/p>\n<p>Alla Paganella \u00e8 andato in scena il primo, dei due appuntamenti, del circuito di\u00a0Coppa Europa\u00a0di sci alpino con lo slalom gigante femminile. Sorridono i colori del\u00a0Comitato FISI Alpi Centrali\u00a0con la terza piazza assoluta, prima azzurra, per\u00a0Nicole Agnelli\u00a0nella gara vinta dalla francese Sophie Anne Barthet. Dietro di lei la connazionale Marion Betrand.<\/p>\n<p>&nbsp;<\/p>\n<p>Per quanto riguarda i colori \u201crosa\u201d del\u00a0Comitato FISI Alpi Centrali\u00a0da segnalare l&#8217;undicesima piazza assoluta per\u00a0Michela Azzola\u00a0ed il 35esimo posto per\u00a0Jole Galli. Non si \u00e8 qualificata, invece, per la seconda manche Ida Giardini.\u00a0Out nella seconda frazione di gara\u00a0Roberta Melesi, mentre sono uscite nella prima manche sia\u00a0Alessia Medetti\u00a0sia\u00a0Sabrina Fanchini.<\/p>\n<p>&nbsp;<\/p>\n<p>Domani, sempre alla Paganella di scena lo slalom speciale.<\/p>\n<p>&nbsp;<\/p>\n<p>Marco Cerottini<\/p>\n<p>Uff. \u00a0stampa Comitato Alpi Centrali<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Nella foto Nicole Agnelli &#8212; \u00a0 Alla Paganella \u00e8 andato in scena il primo, dei due appuntamenti, del circuito di\u00a0Coppa Europa\u00a0di sci alpino con lo slalom gigante femminile. Sorridono i colori del\u00a0Comitato FISI Alpi Centrali\u00a0con la terza piazza assoluta, prima azzurra, per\u00a0Nicole Agnelli\u00a0nella gara vinta dalla francese Sophie Anne Barthet. Dietro di lei la connazionale Marion Betrand. &nbsp; Per quanto&hellip;<\/p>\n","protected":false},"author":4,"featured_media":543603,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/543583"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=543583"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/543583\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/543603"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=543583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=543583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=543583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}