{"id":502241,"date":"2013-10-16T14:32:36","date_gmt":"2013-10-16T12:32:36","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=502241"},"modified":"2013-10-16T14:32:36","modified_gmt":"2013-10-16T12:32:36","slug":"16102013-da-sabato-si-scia-sul-presena","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2013\/10\/16\/16102013-da-sabato-si-scia-sul-presena\/","title":{"rendered":"16\/10\/2013 Da sabato si scia sul Presena"},"content":{"rendered":"<p><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/16102013-da-sabato-si-scia-sul-presena\/presena-3\/\" rel=\"attachment wp-att-502270\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-502270\" alt=\"presena\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/10\/presena.jpg\" width=\"450\" height=\"211\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/10\/presena.jpg 450w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/10\/presena-300x141.jpg 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/a><\/p>\n<p>Che l\u2019inverno abbia inizio: da sabato 19 ottobre sar\u00e0 possibile cominciare a sciare nel comprensorio Adamello Ski. Oltre un metro di neve fresca, scesa lo scorso fine settimana ai 3.000 metri di quota del Presena, \u00e8 andata ad aggiungersi alla neve rimasta sul ghiacciaio grazie alla protezione dei teli geotessili dal sole estivo, permettendoci cos\u00ec di offrire agli appassionati di sci un anticipo di stagione. Gi\u00e0 perch\u00e9 la stagione invernale inizier\u00e0 ufficialmente il 26 ottobre: questo \u00e8 un anticipo di inverno, che salutiamo come buon auspicio per una stagione che ci auguriamo ricca di neve su tutti i nostri 100 km di piste.<\/p>\n<p>Da sabato dunque gli appassionati di sci che vorranno salire sul ghiacciaio troveranno a loro disposizione la pista Presena destra, una \u201crossa\u201d lunga un chilometro che si snoda da 3.016 mt a 2.738 mt di quota. Gli impianti del ghiacciaio saranno in funzione dalle 8 alle 15, lo skipass giornaliero costa \u20ac 27 che diventano \u20ac 24 per i ragazzi (fino a 14 anni di et\u00e0).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Che l\u2019inverno abbia inizio: da sabato 19 ottobre sar\u00e0 possibile cominciare a sciare nel comprensorio Adamello Ski. Oltre un metro di neve fresca, scesa lo scorso fine settimana ai 3.000 metri di quota del Presena, \u00e8 andata ad aggiungersi alla neve rimasta sul ghiacciaio grazie alla protezione dei teli geotessili dal sole estivo, permettendoci cos\u00ec di offrire agli appassionati di&hellip;<\/p>\n","protected":false},"author":4,"featured_media":502242,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[22,9,10],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/502241"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=502241"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/502241\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/502242"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=502241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=502241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=502241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}