{"id":502203,"date":"2013-10-12T16:03:25","date_gmt":"2013-10-12T14:03:25","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=502203"},"modified":"2013-10-12T16:03:25","modified_gmt":"2013-10-12T14:03:25","slug":"12102013-direttori-di-gara-primo-aggiornamento-della-nuova-stagione","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2013\/10\/12\/12102013-direttori-di-gara-primo-aggiornamento-della-nuova-stagione\/","title":{"rendered":"12\/10\/2013 &#8211; DIRETTORI DI GARA: PRIMO AGGIORNAMENTO DELLA NUOVA STAGIONE."},"content":{"rendered":"<p>Il Comitato Alpi Centrali nel 2010 ha istituito nel suo interno la figura delDirettore di Gara, creando anche un apposito Albo. Dalla stagione 2012\/2013 la FISI ha inserito nei suoi regolamenti\u00a0l\u2019indicazione di tale ruolo.Ritenendo tale figura fondamentale e credendo nell\u2019importanza del ruolo assunto, il\u00a0Comitato FISI Alpi Centrali\u00a0ha continuato in questi anni ad aggiornare i Direttori di Gara, creandone anche nuovi con corsi di formazione.<\/p>\n<p>&nbsp;<\/p>\n<p>Attualmente l\u2019Albo del Comitato FISI Alpi Centrali pu\u00f2 vantare ben 211 direttori di gara per la disciplina dello sci alpino e 41 per il settore dello sci di fondo. Per la nuova stagione, sono stati programmati 3 aggiornamenti e una formazione di alpino e un aggiornamento e un corso di fondo.<\/p>\n<p>&nbsp;<\/p>\n<p>Il primo aggiornamento si \u00e8 svolto sabato a Bergamo presso la Casa dello Sport, sede anche del Comitato Provinciale FISI, alla presenza di 16 direttori di gara. I prossimi appuntamenti sono previsti per il prossimo fine settimana a Milano nelle giornate di sabato e domenica. Sempre domenica \u00e8 previsto anche il nuovo corso di formazione, dove al momento risultano gi\u00e0 iscritti 10 nuovi \u201celementi\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Per quanto riguarda invece gli sci stretti aggiornamento e formazione si svolgeranno sempre nella sede di Milano sabato 26 ottobre, ed al momento sono pervenute 5 nuove richieste.<\/p>\n<p>&nbsp;<\/p>\n<p>Marco Cerottini<\/p>\n<p>Ufficio stampa Comitato FISI Alpi Centrali<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Comitato Alpi Centrali nel 2010 ha istituito nel suo interno la figura delDirettore di Gara, creando anche un apposito Albo. Dalla stagione 2012\/2013 la FISI ha inserito nei suoi regolamenti\u00a0l\u2019indicazione di tale ruolo.Ritenendo tale figura fondamentale e credendo nell\u2019importanza del ruolo assunto, il\u00a0Comitato FISI Alpi Centrali\u00a0ha continuato in questi anni ad aggiornare i Direttori di Gara, creandone anche nuovi&hellip;<\/p>\n","protected":false},"author":4,"featured_media":502204,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/502203"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=502203"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/502203\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/502204"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=502203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=502203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=502203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}