{"id":501636,"date":"2013-09-24T23:21:09","date_gmt":"2013-09-24T21:21:09","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=501636"},"modified":"2013-09-24T23:21:09","modified_gmt":"2013-09-24T21:21:09","slug":"2492013-i-ragazzi-del-comitato-fisi-alpi-centrali-a-roma-due-giorni-di-forti-emozioni","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2013\/09\/24\/2492013-i-ragazzi-del-comitato-fisi-alpi-centrali-a-roma-due-giorni-di-forti-emozioni\/","title":{"rendered":"24\/9\/2013 &#8211; I RAGAZZI DEL COMITATO FISI ALPI CENTRALI A ROMA: DUE GIORNI DI FORTI EMOZIONI"},"content":{"rendered":"<p><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/2492013-i-ragazzi-del-comitato-fisi-alpi-centrali-a-roma-due-giorni-di-forti-emozioni\/roma_atletiac2\/\" rel=\"attachment wp-att-501640\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-501640\" alt=\"roma_atletiac2\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/09\/roma_atletiac2.jpg\" width=\"600\" height=\"450\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/09\/roma_atletiac2.jpg 600w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/09\/roma_atletiac2-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a>\u00a0<\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">Dopo le medaglie conquistate agli <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>EYOF<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"> (Festival Europeo della Giovent\u00f9 Olimpica) di <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Brasov<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"> (Romania) sono arrivati prestigiosi riconoscimenti per le giovani speranze italiane degli sport invernali, impegnati a <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Roma<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"> in una due giorni emozionanti. <\/span><\/span><\/p>\n<p align=\"JUSTIFY\">\u00a0<\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">Ieri al <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Quirinale<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"> hanno preso parte alla cerimonia di apertura dell\u2019anno scolastico alla presenza del <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Presidente della Repubblica Giorgio Napolitano<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">. Oggi, invece, sono stati ricevuti dal <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Presidente del CONI Giovanni Malag\u00f2<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">. La delegazione della Federazione Sport Invernali \u00e8 stata la piu\u2019 numerosa ed era composta dai ragazzi del <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Comitato FISI Alpi Centrali<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">: <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Tommaso Sala<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">, <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Roberta Melesi<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">, e <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Veronica Olivieri<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"> a cui si sono aggiunti anche <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Federico Liberatore Hannes Zingerle, Nicole Delago, Verena Gasslitter, Elisa Profanter e Francesca Gallina<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"> (snowboard) e <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Mikael Abram<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"> (fondo). La delegazione \u00e8 stata guidata dal direttore agonistico del settore giovanile dello sci alpino <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Alessandro Serra<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">. <\/span><\/span><\/p>\n<p align=\"JUSTIFY\">\u00a0<\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">Nella sala d\u2019onore del CONI, questa mattina, i giovani azzurri sono stati investiti del titolo di \u201c<\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Ambasciatori dello Sport fra i Giovani<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">&#8220;, un riconoscimento di grande importanza che porter\u00e0 i giovani atleti a rendersi portatori sul proprio territorio dei valori universali dello sport e dell&#8217;olimpismo. <\/span><\/span><\/p>\n<p align=\"JUSTIFY\">\u00a0<\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">Si tratta di un riconoscimento di grande importanza per i Giovani Azzurri che diventeranno dei punti di riferimento per tutti i ragazzi che praticano gli sport invernali.<\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/2492013-i-ragazzi-del-comitato-fisi-alpi-centrali-a-roma-due-giorni-di-forti-emozioni\/roma_atletiac002\/\" rel=\"attachment wp-att-501641\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-501641\" alt=\"roma_atletiac002\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/09\/roma_atletiac002.jpg\" width=\"300\" height=\"400\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/09\/roma_atletiac002.jpg 300w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/09\/roma_atletiac002-225x300.jpg 225w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p align=\"JUSTIFY\">\u00a0<\/p>\n<p align=\"RIGHT\">\u00a0<\/p>\n<p align=\"RIGHT\"><span style=\"font-family: Arial, sans-serif\">Marco Cerottini<\/span><\/p>\n<p align=\"RIGHT\"><span style=\"font-family: Arial, sans-serif\">Ufficio stampa Comitato FISI Alpi Centrali<\/span><\/p>\n<p align=\"RIGHT\"><span style=\"font-family: Arial, sans-serif\">Tel.: 3475791302<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Dopo le medaglie conquistate agli EYOF (Festival Europeo della Giovent\u00f9 Olimpica) di Brasov (Romania) sono arrivati prestigiosi riconoscimenti per le giovani speranze italiane degli sport invernali, impegnati a Roma in una due giorni emozionanti. \u00a0 Ieri al Quirinale hanno preso parte alla cerimonia di apertura dell\u2019anno scolastico alla presenza del Presidente della Repubblica Giorgio Napolitano. Oggi, invece, sono stati&hellip;<\/p>\n","protected":false},"author":4,"featured_media":501637,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/501636"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=501636"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/501636\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/501637"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=501636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=501636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=501636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}