{"id":501358,"date":"2013-09-17T15:36:02","date_gmt":"2013-09-17T13:36:02","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=501358"},"modified":"2013-09-17T15:36:02","modified_gmt":"2013-09-17T13:36:02","slug":"1792013-sci-alpino-test-positivi-al-passo-dello-stelvio-nonostante-il-maltempo","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2013\/09\/17\/1792013-sci-alpino-test-positivi-al-passo-dello-stelvio-nonostante-il-maltempo\/","title":{"rendered":"17\/9\/2013 &#8211; SCI ALPINO: TEST POSITIVI AL PASSO DELLO STELVIO NONOSTANTE IL MALTEMPO"},"content":{"rendered":"<p><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/1792013-sci-alpino-test-positivi-al-passo-dello-stelvio-nonostante-il-maltempo\/sqmaschilestelvio2\/\" rel=\"attachment wp-att-501365\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-501365\" alt=\"SqMaschileStelvio2\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/09\/SqMaschileStelvio2.jpg\" width=\"600\" height=\"450\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/09\/SqMaschileStelvio2.jpg 600w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/09\/SqMaschileStelvio2-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a>\u00a0<\/p>\n<p>E\u2019 terminato quest\u2019oggi il primo collettivo delle formazioni maschile e femminile dello sci alpino \u201ctargato\u201d\u00a0Comitato FISI Alpi Centrali\u00a0che dopo la pausa estiva si sono ritrovati al\u00a0Passo dello Stelvio\u00a0per una 4 giorni di allenamento.<\/p>\n<p>&nbsp;<\/p>\n<p>Collettivo segnato particolarmente dalle avverse condizioni meteo che hanno costretto a rivedere i piani dei tecnici\u00a0Simone Stiletto\u00a0ed\u00a0Elio Presazzi\u00a0che, comunque, si sono detti soddisfatti del lavoro svolto in questo primo raduno.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cDi quattro giorni \u2013 hanno commentato \u2013 uno \u00e8 stato fatto in palestra a causa delle avverse condizioni meteo. Nonostante questo, la preparazione di tutti i ragazzi \u00e8 soddisfacente grazie, anche, al proficuo lavoro svolto dagli atleti con i loro sci club durante l\u2019estate. Abbiamo incentrato il nostro lavoro prevalentemente sullo slalom gigante, anche se era nostra intenzione fare qualche curva fra i pali stretti, ma il meteo si \u00e8 opposto.\u201d<\/p>\n<p>&nbsp;<\/p>\n<p>Gi\u00e0 calendarizzato il prossimo collettivo che si svolger\u00e0 dal 24 al 27 settembre prossimo sulle nevi di\u00a0Hintertux. In questa occasione Stiletto e Presazzi punteranno tutto sulla velocit\u00e0. Quattro giorni di lavoro dedicati al supergigante, discesa e slalom gigante.<\/p>\n<p>&nbsp;<\/p>\n<p>Qui di seguito i convocati, \u00a0maschili e femminili:<\/p>\n<p>Matteo Baraffuladi, Matteo Confortola, Marco Furli, Pier Francesco Monaci, Alessio Scilligo, Dino Tanghetti,\u00a0Angelica Casartelli, Jole Galli, Giulia Lorini, Roberta Midali, Martina Nobis, Ymer Sola<\/p>\n<p>Si unir\u00e0 alla squadra anche il gruppo controllati composto da: Nicholas Bellini, Filippo Beretta, Guido Malzanni, Pietro Migliazza, Filippo Nana, Pietro Zazzi, Elisa Bianchi Bazzi, Gaia Martinelli, Alessia Minazzi, Sharon Salomoni, Petra Smaldore e Virginia Sosio.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Marco Cerottini<\/p>\n<p>Ufficio stampa Comitato FISI Alpi Centrali<\/p>\n<p>Tel.:\u00a0<a href=\"tel:3475791302\">3475791302<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 E\u2019 terminato quest\u2019oggi il primo collettivo delle formazioni maschile e femminile dello sci alpino \u201ctargato\u201d\u00a0Comitato FISI Alpi Centrali\u00a0che dopo la pausa estiva si sono ritrovati al\u00a0Passo dello Stelvio\u00a0per una 4 giorni di allenamento. &nbsp; Collettivo segnato particolarmente dalle avverse condizioni meteo che hanno costretto a rivedere i piani dei tecnici\u00a0Simone Stiletto\u00a0ed\u00a0Elio Presazzi\u00a0che, comunque, si sono detti soddisfatti del lavoro&hellip;<\/p>\n","protected":false},"author":4,"featured_media":501359,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/501358"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=501358"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/501358\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/501359"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=501358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=501358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=501358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}