{"id":501205,"date":"2013-08-17T22:12:48","date_gmt":"2013-08-17T20:12:48","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=501205"},"modified":"2013-08-17T22:12:48","modified_gmt":"2013-08-17T20:12:48","slug":"1782013-sci-alpino-concluso-lo-stage-dallenamento-per-i-ragazzi-del-comitato-alpi-centrali-con-la-nazionale","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2013\/08\/17\/1782013-sci-alpino-concluso-lo-stage-dallenamento-per-i-ragazzi-del-comitato-alpi-centrali-con-la-nazionale\/","title":{"rendered":"17\/8\/2013 &#8211; SCI ALPINO: Concluso lo stage d&#8217;allenamento per i ragazzi del Comitato A C  con la Nazionale"},"content":{"rendered":"<p align=\"JUSTIFY\"><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/1782013-sci-alpino-concluso-lo-stage-dallenamento-per-i-ragazzi-del-comitato-alpi-centrali-con-la-nazionale\/accompagnatoriac\/\" rel=\"attachment wp-att-501211\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-501211\" alt=\"accompagnatoriac\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/08\/accompagnatoriac.jpg\" width=\"600\" height=\"338\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/08\/accompagnatoriac.jpg 600w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/08\/accompagnatoriac-300x169.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-size: medium\">Si \u00e8 concluso oggi dopo una bellissima quattro giorni di sci, tra l&#8217;entusiasmo e l&#8217;emozione dei partecipanti, il primo &#8220;Junior stage&#8221; dello sci alpino sul ghiacciaio del Plateau Ros\u00e0 a Cervinia. <\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-size: medium\">\u00a0<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-size: medium\">Il raduno si \u00e8 aperto nel pomeriggio di marted\u00ec 13 Agosto alla presenza del Presidente Federale Flavio Roda che ha dato il benvenuto agli atleti, 19 maschi e 22 femmine, selezionati tra i migliori atleti allievi ed aspiranti di tutti i Comitati Regionali. Oltre al Presidente Nazionale che \u00e8 rimasto con tutto il gruppo fino a gioved\u00ec 15 agosto, presenti anche il direttore tecnico nazionale giovanile Alessandro Serra ed i responsabili nazionali maschile e femminile Devid Salvadori e Roberto Lorenzi che hanno diretto i 41 atleti presenti che, di buona lena, si sono messi a disposizione degli allenatori sulle due piste messe a disposizione dalla struttura sciistica. <\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-size: medium\">Per i primi due giorni il gruppo maschile si \u00e8 allenato in Gigante mentre il gruppo femminile in Slalom, parti e piste invertite per le restanti due giornate.<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-size: medium\">\u00a0<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-size: medium\">Per il nostro <b>Comitato Regionale<\/b>, erano presenti 8 atleti, 4 maschi e 4 femmine: <\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-size: medium\">&#8211; Chiara Cabello 1997 AS Caspoggio<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-size: medium\">&#8211; Marika Mascherona 1998 SC Bormio<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-size: medium\">&#8211; Alessia Minazzi 1997 SC San Domenico<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-size: medium\">&#8211; Virginia Sosio 1997 SC Bormio<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-size: medium\">\u00a0<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-size: medium\">&#8211; Nicol\u00f2 Molteni 1998 SC Lecco<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-size: medium\">&#8211; Lorenzo Moschini 1997 SC Collio<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-size: medium\">&#8211; Luca Ruschetta 1997 SC San Domenico<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-size: medium\">&#8211; Federico Tomasoni 1997 SC Ubi Banca Goggi<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-size: medium\"><span style=\"font-family: Arial, sans-serif\">che, coordinati dall\u2019allenatore regionale <\/span><span style=\"font-family: Arial, sans-serif\"><b>Elio Presazzi<\/b><\/span><span style=\"font-family: Arial, sans-serif\">, coadiuvato da <\/span><span style=\"font-family: Arial, sans-serif\"><b>Corrado Minazzi<\/b><\/span><span style=\"font-family: Arial, sans-serif\">, <\/span><span style=\"font-family: Arial, sans-serif\"><b>Riccardo Ruschetta<\/b><\/span><span style=\"font-family: Arial, sans-serif\"> e <\/span><span style=\"font-family: Arial, sans-serif\"><b>Marcello Tavola<\/b><\/span><span style=\"font-family: Arial, sans-serif\">, hanno avuto la possibilit\u00e0 di confrontarsi in questo stage con i migliori atleti della stessa categoria a livello nazionale.<\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-size: medium\">\u00a0<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-size: medium\">\u201c<span style=\"font-family: Arial, sans-serif\">Esperienza assolutamente positiva e sicuramente da ripetersi &#8211; commenta Elio Presazzi &#8211; aiutati sicuramente anche dal tempo fantastico e da una neve ottimale che ci hanno permesso di condurre un ottimo lavoro per ben quattro giorni\u201d.<\/span><\/span><\/p>\n<p align=\"JUSTIFY\">\u00a0<\/p>\n<p><span style=\"color: #000000\">\u00a0<\/span><\/p>\n<p align=\"RIGHT\"><span style=\"font-family: Arial, sans-serif\">Marco Cerottini<\/span><\/p>\n<p align=\"RIGHT\"><span style=\"font-family: Arial, sans-serif\">Ufficio stampa Comitato FISI Alpi Centrali<\/span><\/p>\n<p align=\"RIGHT\"><span style=\"font-family: Arial, sans-serif\">Tel.: 3475791302<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si \u00e8 concluso oggi dopo una bellissima quattro giorni di sci, tra l&#8217;entusiasmo e l&#8217;emozione dei partecipanti, il primo &#8220;Junior stage&#8221; dello sci alpino sul ghiacciaio del Plateau Ros\u00e0 a Cervinia. \u00a0 Il raduno si \u00e8 aperto nel pomeriggio di marted\u00ec 13 Agosto alla presenza del Presidente Federale Flavio Roda che ha dato il benvenuto agli atleti, 19 maschi e&hellip;<\/p>\n","protected":false},"author":4,"featured_media":501207,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/501205"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=501205"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/501205\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/501207"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=501205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=501205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=501205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}