{"id":500747,"date":"2013-06-25T16:01:47","date_gmt":"2013-06-25T14:01:47","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=500747"},"modified":"2013-06-25T16:01:47","modified_gmt":"2013-06-25T14:01:47","slug":"assemblea-federale-straordinaria-statuto-2013-modifiche-ed-integrazioni","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2013\/06\/25\/assemblea-federale-straordinaria-statuto-2013-modifiche-ed-integrazioni\/","title":{"rendered":"Assemblea Federale Straordinaria Statuto 2013 &#8211; Modifiche ed Integrazioni"},"content":{"rendered":"<p>Il Consiglio Federale del 22 giugno 2013, a seguito di segnalazioni e proposte di alcuni\u00a0 Associati ed a seguito di rivisitazione del testo da parte della Commissione per la revisione dello Statuto, ha approvato l\u2019integrazione del testo dello Statuto federale in approvazione all\u2019Assemblea Federale Straordinaria, modificando nella formulazione l&#8217;art.1 punto 6, l&#8217;art.4 punto 9,\u00a0gli art.4 punto 13, 14 punto 13, 26 punto c, 35 punti i e l e 48 punti 2 e 4, l&#8217;art.14, l&#8217;art.41 punti 1 e 2, l&#8217;art.51 punto 5.<\/p>\n<p>Il Nuovo testo di Statuto che recepisce le modifiche e le integrazioni di cui sopra \u00e8 pertanto quello pubblicato sul sito federale.<\/p>\n<p>Link diretto:\u00a0\u00a0<a href=\"https:\/\/www.fisi.org\/node\/51009\">https:\/\/www.fisi.org\/node\/51009<\/a><\/p>\n<p>Con i pi\u00f9 cordiali saluti.<\/p>\n<p>Enrico Negretti<br \/>Direttore Generale<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Consiglio Federale del 22 giugno 2013, a seguito di segnalazioni e proposte di alcuni\u00a0 Associati ed a seguito di rivisitazione del testo da parte della Commissione per la revisione dello Statuto, ha approvato l\u2019integrazione del testo dello Statuto federale in approvazione all\u2019Assemblea Federale Straordinaria, modificando nella formulazione l&#8217;art.1 punto 6, l&#8217;art.4 punto 9,\u00a0gli art.4 punto 13, 14 punto 13,&hellip;<\/p>\n","protected":false},"author":4,"featured_media":500752,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,10],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/500747"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=500747"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/500747\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/500752"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=500747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=500747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=500747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}