{"id":500081,"date":"2013-05-08T22:04:44","date_gmt":"2013-05-08T20:04:44","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=500081"},"modified":"2013-05-08T22:04:44","modified_gmt":"2013-05-08T20:04:44","slug":"852013-sci-di-fondo-ecco-le-squadre-per-la-stagione-2013-2014-massicia-la-presenza-dei-ragazzi-del-comitato-fisi-alpi-centrali","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2013\/05\/08\/852013-sci-di-fondo-ecco-le-squadre-per-la-stagione-2013-2014-massicia-la-presenza-dei-ragazzi-del-comitato-fisi-alpi-centrali\/","title":{"rendered":"8\/5\/2013 &#8211; Sci di Fondo &#8211; Ecco le Squadre per la stagione 2013-2014:massicia la presenza dei ragazzi del Comitato A C"},"content":{"rendered":"<p><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/852013-sci-di-fondo-ecco-le-squadre-per-la-stagione-2013-2014-massicia-la-presenza-dei-ragazzi-del-comitato-fisi-alpi-centrali\/beatrice2\/\" rel=\"attachment wp-att-500120\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-500120\" alt=\"beatrice2\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/05\/beatrice2.jpg\" width=\"400\" height=\"300\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/05\/beatrice2.jpg 400w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/05\/beatrice2-300x225.jpg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-500087\" alt=\"Nicola Fornoni 2013art\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/05\/Nicola-Fornoni-2013art.jpg\" width=\"400\" height=\"300\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/05\/Nicola-Fornoni-2013art.jpg 400w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/05\/Nicola-Fornoni-2013art-300x225.jpg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/852013-sci-di-fondo-ecco-le-squadre-per-la-stagione-2013-2014-massicia-la-presenza-dei-ragazzi-del-comitato-fisi-alpi-centrali\/chiara-zini2\/\" rel=\"attachment wp-att-500094\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-500094\" alt=\"chiara zini2\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/05\/chiara-zini2.jpg\" width=\"400\" height=\"300\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/05\/chiara-zini2.jpg 400w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/05\/chiara-zini2-300x225.jpg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n<p>Nella foto Beatrice Rocca, Nicola Fornoni e Chiara Zini&#8212;&#8211;<\/p>\n<p>&nbsp;<\/p>\n<p>Il Presidente della Federazione Italiana Sport Invernali Flavio Roda alla presenza dei responsabili tecnici, del Vice Presidente Piccin e del Consigliere Atleta Gabriella Paruzzi, ha ufficializzato la composizione delle squadre di sci di fondo per la stagione 2013-2014. Alla vigilia dell\u2019importante appuntamento olimpico di Sochi 2014, la Federazione rivolge il massimo impegno e supporto alle squadre di Coppa del mondo e, in particolar modo, agli atleti che difenderanno i colori dell&#8217;Italia ai prossimi Giochi Olimpici.<\/p>\n<p>&nbsp;<\/p>\n<p>Massiccia la presenza degli atleti del Comitato FISI Alpi Centrali a testimonianza di come il lavoro svolto dai tecnici regionali e dai singoli sci club sia stato prolifico permettendo ai ragazzi delle Alpi Centrali di crescere e dalla prossima stagione di vestire la maglia azzurra.<\/p>\n<p>&nbsp;<\/p>\n<p>La squadra under 23 \u00e8 stata accorpata al gruppo FuturFisi per garantire, anche nell&#8217;anno olimpico, il necessario ricambio al movimento dello sci di fondo e quindi assicurargli un futuro per gli anni a venire. Il progetto FuturFisi dar\u00e0 continuit\u00e0 a quanto gi\u00e0 cominciato nella scorsa stagione coinvolgendo atleti appartenenti alle squadre under 20, under 18 e attraverso la convocazione di altri atleti in stage di allenamento allargati ai Comitati Regionali.<\/p>\n<p>&nbsp;<\/p>\n<p>Di seguito l\u2019elenco degli atleti che comporranno le squadre azzurre e provenienti dal Comitato FISI Alpi Centrali<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>SQUADRA COPPA DEL MONDO MASCHILE<\/p>\n<p>PASINI Fabio\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0&#8211; 1980 &#8211; CS Esercito<\/p>\n<p>SQUADRA A MASCHILE<\/p>\n<p>CLEMENTI Fabio\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 &#8211; 1990 &#8211; CS CARABINIERI<\/p>\n<p>SQUADRA UNDER 23 MASCHILE<\/p>\n<p>BERTOLINA Mirco\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0&#8211; 1991 &#8211; CS FORESTALE<\/p>\n<p>RASTELLI Maicol\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0&#8211; 1991 &#8211;\u00a0 CS ESERCITO<\/p>\n<p>GRUPPO DI INTERESSE NAZIONALE MASCHILE<\/p>\n<p>CLEMENTI Fabrizio\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 &#8211; 1988 &#8211; CS CARABINIERI<\/p>\n<p>GULLO Giovanni\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 &#8211; 1983 &#8211;\u00a0 GS FIAMME GIALLE<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>GRUPPO FUTURFISI<\/p>\n<p>&nbsp;<\/p>\n<p>SQUADRA UNDER 20 MASCHILE<\/p>\n<p>PEROTTI Manuel\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 &#8211; 1994 &#8211; CS FORESTALE<\/p>\n<p>ROMANI Simone\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 &#8211; 1995 &#8211; GS FIAMME GIALLE<\/p>\n<p>SQUADRA UNDER 20 FEMMINILE<\/p>\n<p>CANCLINI Alice\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 &#8211; 1994 &#8211; CS ESERCITO<\/p>\n<p>ROCCA Beatrice\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 &#8211; 1995 &#8211; US ALTA VALTELLINA<\/p>\n<p>OSSERVATI UNDER 20 MASCHILE<\/p>\n<p>VENOSTA Claudio\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0&#8211; 1995 &#8211; POLISPORTIVA LE PRESE<\/p>\n<p>SQUADRA UNDER 18 MASCHILE<\/p>\n<p>FORNONI Nicola\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0&#8211; 1996\u00a0\u2013 CLUSONE<\/p>\n<p>SQUADRA UNDER 18 FEMMINILE<\/p>\n<p>ZINI Chiara\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 &#8211; 1996 \u2013 LIVIGNO<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Marco Cerottini<\/p>\n<p>Comitato \u00a0Alpi Centrali<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nella foto Beatrice Rocca, Nicola Fornoni e Chiara Zini&#8212;&#8211; &nbsp; Il Presidente della Federazione Italiana Sport Invernali Flavio Roda alla presenza dei responsabili tecnici, del Vice Presidente Piccin e del Consigliere Atleta Gabriella Paruzzi, ha ufficializzato la composizione delle squadre di sci di fondo per la stagione 2013-2014. Alla vigilia dell\u2019importante appuntamento olimpico di Sochi 2014, la Federazione rivolge il&hellip;<\/p>\n","protected":false},"author":4,"featured_media":500122,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,10,12],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/500081"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=500081"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/500081\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/500122"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=500081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=500081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=500081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}