{"id":499834,"date":"2013-04-30T15:44:56","date_gmt":"2013-04-30T13:44:56","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=499834"},"modified":"2013-04-30T15:44:56","modified_gmt":"2013-04-30T13:44:56","slug":"3042013-noi-continuiamo-a-sciare-e-voi","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2013\/04\/30\/3042013-noi-continuiamo-a-sciare-e-voi\/","title":{"rendered":"30\/4\/2013 &#8211;\tNOI CONTINUIAMO A SCIARE, E VOI?"},"content":{"rendered":"<div><a title=\"\" href=\"https:\/\/www.adamelloski.com\/images\/News\/2012-2013\/_5d_8415web.jpg\"><span style=\"color: #333333\"><img loading=\"lazy\" decoding=\"async\" title=\"\" alt=\"\" src=\"https:\/\/www.adamelloski.com\/images\/News\/2012-2013\/Miniature230x109\/_5d_8415web.jpg\" width=\"230\" height=\"109\" \/><\/span><\/a><\/div>\n<div>\n<p>Il 30 aprile rappresenta la fine della stagione invernale 2012-2013 nel comprensorio Adamello Ski. Lo sci per\u00f2 non si ferma, dal 1 maggio infatti prende il via la stagione dello sci estivo che proseguir\u00e0 fino al 9 giugno sul ghiacciaio Presena, a 3.000 mt di quota dove le condizioni di innevamento sono ottime. Lo skipass giornaliero adulto coster\u00e0 \u20ac 27 e per la sola giornata del 1 maggio per i possessori di skipass stagionale Adamello Ski, Superskirama \u00a0e Regionale 2012-2013 sar\u00e0 scontato a \u20ac 10.<\/p>\n<p>La stagione appena conclusa \u00e8 stata piuttosto lunga ed ha visto il comprensorio Adamello Ski crescere ulteriormente: sono state investite nuove risorse per l\u2019ammodernamento di alcuni impianti di risalita, la seggiovia 6 posti Vittoria ed il tapis roulant coperto \u201cTubbo\u201d, che hanno riscosso un buon successo, ed \u00e8 stato realizzato un secondo snowpark al Passo Tonale. Nuove attivit\u00e0, lo snow kite ed i go kart, si sono aggiunte alle altre gi\u00e0 presenti in localit\u00e0 (sci nordico, sleddog, motoslitte, pattinaggio) ed il centro fondo di Pontedilegno (Val Sozzine) si \u00e8 aggiunto a quelli del Tonale e di Vermiglio, inoltre sono stati realizzati 4 nuovi itinerari per le ciaspole tra Pontedilegno ed il Tonale arricchendo cos\u00ec le offerte a disposizione dei turisti. Abbiamo investito molto sulla famiglia: sono state riproposte le attivit\u00e0 Fun Kids sulla neve per i pi\u00f9 piccoli ed \u00e8 stata introdotta la gratuit\u00e0 per i bambini fino a 8 anni accompagnati da un adulto pagante. Sono stati organizzati vari eventi ed attivit\u00e0 per giovani nei week end ed \u00e8 stata organizzata la 4^ edizione dell\u2019Adamello Ski Raid, una delle pi\u00f9 prestigiose gare di sci alpinismo che ha portato a Pontedilegno-Tonale i pi\u00f9 forti atleti del mondo di questa specialit\u00e0.<\/p>\n<p>Per il comprensorio Adamello Ski \u00e8 un motivo d\u2019orgoglio l\u2019attribuzione del 4\u00b0 posto della pista Paradiso nella classifica delle rivista SCI che ha chiesto ai suoi lettori di votare le piste pi\u00f9 belle. I 17.411 votanti hanno eletto quarta la pista Paradiso, una \u201cnera\u201d che scende dal passo Paradiso al passo Tonale per 3 km ed un dislivello di 737 metri, che \u00e8 risalita cos\u00ec di 14 posizioni rispetto al medesimo sondaggio dell\u2019anno scorso. \u201cSiamo molto soddisfatti di questo riconoscimento che ho avuto l\u2019onore di ricevere dalle mani di Gustav Thoeni e di Peter Runggaldier alla fiera Prowinter di Bolzano.- spiega il direttore del Consorzio Adamello Ski Giovanni Malcotti- La pista Paradiso si conferma una delle piste pi\u00f9 amate d\u2019Italia dagli appassionati di sci\u201d.<\/p>\n<p> Pontedilegno, 30 aprile 2013<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il 30 aprile rappresenta la fine della stagione invernale 2012-2013 nel comprensorio Adamello Ski. Lo sci per\u00f2 non si ferma, dal 1 maggio infatti prende il via la stagione dello sci estivo che proseguir\u00e0 fino al 9 giugno sul ghiacciaio Presena, a 3.000 mt di quota dove le condizioni di innevamento sono ottime. Lo skipass giornaliero adulto coster\u00e0 \u20ac 27&hellip;<\/p>\n","protected":false},"author":4,"featured_media":499811,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,10],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/499834"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=499834"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/499834\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/499811"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=499834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=499834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=499834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}