{"id":498678,"date":"2013-04-06T17:01:51","date_gmt":"2013-04-06T15:01:51","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=498678"},"modified":"2013-04-06T17:01:51","modified_gmt":"2013-04-06T15:01:51","slug":"criterium-nazionale-cuccioli-oro-per-gli-atleti-alpi-centrali-alessia-guerinoni-e-francesco-bertocchi","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2013\/04\/06\/criterium-nazionale-cuccioli-oro-per-gli-atleti-alpi-centrali-alessia-guerinoni-e-francesco-bertocchi\/","title":{"rendered":"Criterium Nazionale Cuccioli: Oro per gli atleti Alpi Centrali Alessia Guerinoni e Francesco Bertocchi"},"content":{"rendered":"<p><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/criterium-nazionale-cuccioli-oro-per-gli-atleti-alpi-centrali-alessia-guerinoni-e-francesco-bertocchi\/alessia-guerinoniart\/\" rel=\"attachment wp-att-498693\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-498693\" alt=\"Alessia Guerinoniart\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/04\/Alessia-Guerinoniart.jpg\" width=\"300\" height=\"343\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/04\/Alessia-Guerinoniart.jpg 300w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/04\/Alessia-Guerinoniart-262x300.jpg 262w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\u00a0<\/p>\n<p>Nella prima giornata di gare a Cortina grande successo per le Alpi Centrali con due medaglie d&#8217;oro conquistate da Alessia Guerinoni nella GK veloce per l&#8217;anno 2002 e Francesco Bertocchi nello Slalom per l&#8217;anno 2001.<\/p>\n<p><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/criterium-nazionale-cuccioli-oro-per-gli-atleti-alpi-centrali-alessia-guerinoni-e-francesco-bertocchi\/bertocchi-francescoart\/\" rel=\"attachment wp-att-498694\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-498694\" alt=\"Bertocchi Francescoart\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/04\/Bertocchi-Francescoart.jpg\" width=\"300\" height=\"423\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/04\/Bertocchi-Francescoart.jpg 300w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/04\/Bertocchi-Francescoart-213x300.jpg 213w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Oggi poi troviamo altri ottimi piazzamenti nella GK anno 2002 tra gli atleti delle Alpi Centrali: Nadia Fenini 5^, Alessandra Mora 16^ e Giorgia Misseri 17^ tra le femmine, Ian Rocca 7\u00b0, Luca Cremaschini 18\u00b0 e Mattia Fiaccadori 20\u00b0 tra i maschi.<\/p>\n<p>Per l&#8217;anno 2001 nello slalom sempre tra i primi venti classificati oltre al vincitore in campo maschile troviamo l&#8217;ottima \u00a0Benedetta Sosio 12^ in campo femminile.<\/p>\n<p>Per le classifiche complete:<a href=\"https:\/\/www.sciclubcortina.it\/criteriumcuccioli\/news.php\">https:\/\/www.sciclubcortina.it\/criteriumcuccioli\/news.php<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Nella prima giornata di gare a Cortina grande successo per le Alpi Centrali con due medaglie d&#8217;oro conquistate da Alessia Guerinoni nella GK veloce per l&#8217;anno 2002 e Francesco Bertocchi nello Slalom per l&#8217;anno 2001. &nbsp; Oggi poi troviamo altri ottimi piazzamenti nella GK anno 2002 tra gli atleti delle Alpi Centrali: Nadia Fenini 5^, Alessandra Mora 16^ e&hellip;<\/p>\n","protected":false},"author":4,"featured_media":498452,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/498678"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=498678"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/498678\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/498452"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=498678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=498678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=498678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}