{"id":498159,"date":"2013-04-02T22:47:19","date_gmt":"2013-04-02T20:47:19","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=498159"},"modified":"2013-04-02T22:47:19","modified_gmt":"2013-04-02T20:47:19","slug":"edoardo-zorzi-ai-campionati-italiani-ski-cross-in-valmalenco","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2013\/04\/02\/edoardo-zorzi-ai-campionati-italiani-ski-cross-in-valmalenco\/","title":{"rendered":"Campionati Italiani Ski Cross in Valmalenco"},"content":{"rendered":"<p>Marco Tomasi coglie il primo titolo italiano della carriera nella gara disputata sulla pista di Valmalenco in contemporanea con lo snowboardcross. Il venticinquenne bolzanino di origini vicentine, tesserato per l&#8217;Esercito e brillante protagonista nelle scorse settimane nei Mondiali conclusi all&#8217;ottavo posto, ha preceduto nella finale a quattro Stefan Thanei (Forestale) e Stephan Miribung (CS Esercito), mentre Diego Castellaz \u00e8 uscito nel corso della prima run.<\/p>\n<p>Fra gli juniores successo del bergamasco Edoardo Zorzi su William Cappelletti e Isacco Carrara. In campo femminile successo di Debora Pixner che migliora il terzo posto ottenuto nell&#8217;edizione dell&#8217;anno passato, alle sue spalle Sabine Wolfsgruber (Leistungszentrum Kronplatz Ski Alpin ASV) e Margherita Enrietti (Aosta Snowboard Club ASD).<\/p>\n<p>Il programma riserva nel weekend le prossime gare: si comincia sabato 6 con le Dual Moguls, seguite domenica 7 aprile dalle Moguls.<\/p>\n<p>Ordine d&#8217;arrivo SX maschile Campionati Italiani seniores Valmalenco (Ita): 1. Marco Tomasi (CS Esercito) 2. Stefan Thanei (CS Forestale) 3. Stephan Miribung (CS Esercito) 4. Francesco Veluschek (Sci CAI Monte Lussari ASD)<\/p>\n<p>Ordine d&#8217;arrivo SX maschile Campionati Italiani juniores Valmalenco (Ita): 1. Edoardo Zorzi (SC Radici Group) 2. William Cappelletti (ASD Club de Ski Valtournenche) 3. Isacco Carrara (SC 90 Montecampione) Ordine d&#8217;arrivo SX femminile Campionati Italiani seniores e juniores Valmalenco (Ita): 1. Debora Pixner (Amateursportclub Passeier) 2. Sabine Wolfsgruber (Leistungszentrum Kronplatz Ski Alpin ASV) 3. Margherita Enrietti (Aosta snowboard Club ASD)<\/p>\n<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/edoardo-zorzi-ai-campionati-italiani-ski-cross-in-valmalenco\/zorzi\/\" rel=\"attachment wp-att-498158\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-498158\" alt=\"ZORZI\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/04\/ZORZI.jpg\" width=\"450\" height=\"380\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/04\/ZORZI.jpg 450w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/04\/ZORZI-300x253.jpg 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Edoardo Zorzi si e&#8217; classificato primo tra i &#8220;giovani&#8221; oggi in Valmalenco<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marco Tomasi coglie il primo titolo italiano della carriera nella gara disputata sulla pista di Valmalenco in contemporanea con lo snowboardcross. Il venticinquenne bolzanino di origini vicentine, tesserato per l&#8217;Esercito e brillante protagonista nelle scorse settimane nei Mondiali conclusi all&#8217;ottavo posto, ha preceduto nella finale a quattro Stefan Thanei (Forestale) e Stephan Miribung (CS Esercito), mentre Diego Castellaz \u00e8 uscito&hellip;<\/p>\n","protected":false},"author":4,"featured_media":498165,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[13,9,10],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/498159"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=498159"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/498159\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/498165"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=498159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=498159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=498159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}