{"id":497811,"date":"2013-03-27T14:48:33","date_gmt":"2013-03-27T13:48:33","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=497811"},"modified":"2013-03-27T14:48:33","modified_gmt":"2013-03-27T13:48:33","slug":"campo-felice-oggi-giornata-di-super-gigante-ragazzi-e-di-slalom-gigante-allievi","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2013\/03\/27\/campo-felice-oggi-giornata-di-super-gigante-ragazzi-e-di-slalom-gigante-allievi\/","title":{"rendered":"27\/3\/2013 &#8211;  CAMPO FELICE: OGGI GIORNATA DI SUPER GIGANTE RAGAZZI E DI SLALOM GIGANTE ALLIEVI"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Nella prova di super gigante valido per l\u2019assegnazione del titolo nazionale per la categoria Ragazzi, in campo femminile si \u00e8 imposta la piemontese Veronika Calati. Ottimo il quinto posto di Carlina Pozzi dello sci club Bormio. \u00a0Nei primi quindi anche Silvia Turla dello Ski Team Valpalot che centra la 13esima posizione. In campo maschile, invece \u00e8 stato il veneto Davide Filippo (Centro Vicenza) ha conquistare il titolo. Ottavo Davide Barufaldi dello sci club Lecco, seguito da Andrea Steviano dello sci club Valmalendo. Nei primi quindici anche Emanuele Radici dello sci club Radici Group.<\/p>\n<p>&nbsp;<\/p>\n<p>In gara quast\u2019oggi anche la categoria Allievi che hanno affrontato la prova di slalom gigante. In campo maschile si \u00e8 imposto Andrea Beltrame del CAI XXX Ottobre. Quinta piazza, invece, per Alessandro Gianotti dello sci club Livigno seguito, in sesta piazza, per Federico Tommasoni dello sci club Ubi Banca Goggi. Bene anche Nicol\u00f2 Molteni dello sci club Lecco che centra l\u2019ottava piazza e portando a tre i ragazzi del Comitato FISI Alpi Centrali nelle prime dieci posizioni<\/p>\n<p>&nbsp;<\/p>\n<p>In campo femminile la medaglia d\u2019oro \u00e8 andata a Elisa Fornari dello sci club Aosta. Peccato per Petra Smaldore (SC Derviese) che ha raccolta la quarta piazza ai piedi, dunque, del podio. Nei primi quindici anche Angelica Rizzi (Ski Team Valpalot) e Alessia Minazzi dello sci club San Domenico<\/p>\n<p><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/wp-content\/uploads\/2013\/03\/2013057_00095M00002_04_00005_Classifica_Finale_A_M.pdf\" target=\"_blank\" rel=\"noopener\"><\/p>\n<p>\u00a0Classifica All M<\/p>\n<p><\/a><\/p>\n<p><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/wp-content\/uploads\/2013\/03\/2013057_00095M00002_04_00005_Classifica_Finale_A_F.pdf\" target=\"_blank\" rel=\"noopener\">Classifica All F<\/a><\/p>\n<p><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/wp-content\/uploads\/2013\/03\/2013057_00096M00001_04_00005_Classifica_Finale_R_M-1.pdf\" target=\"_blank\" rel=\"noopener\"><\/p>\n<p>Classifica Rag M\u00a0<\/p>\n<p><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/wp-content\/uploads\/2013\/03\/2013057_00096M00001_04_00005_Classifica_Finale_R_F.pdf\" target=\"_blank\" rel=\"noopener\"><\/p>\n<p>Classifica Rag F<\/p>\n<p><\/a><\/p>\n<p><\/a><\/p>\n<p>Marco Cerottini<\/p>\n<p>X Fisi Alpi Centrali\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Nella prova di super gigante valido per l\u2019assegnazione del titolo nazionale per la categoria Ragazzi, in campo femminile si \u00e8 imposta la piemontese Veronika Calati. Ottimo il quinto posto di Carlina Pozzi dello sci club Bormio. \u00a0Nei primi quindi anche Silvia Turla dello Ski Team Valpalot che centra la 13esima posizione. In campo maschile, invece \u00e8 stato il veneto&hellip;<\/p>\n","protected":false},"author":4,"featured_media":497813,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/497811"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=497811"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/497811\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/497813"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=497811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=497811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=497811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}