{"id":495981,"date":"2013-03-19T21:25:58","date_gmt":"2013-03-19T20:25:58","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=495981"},"modified":"2013-03-19T21:25:58","modified_gmt":"2013-03-19T20:25:58","slug":"1932013-criterium-italiano-giovani-e-senior-ecco-la-squadra-alpi-centrali","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2013\/03\/19\/1932013-criterium-italiano-giovani-e-senior-ecco-la-squadra-alpi-centrali\/","title":{"rendered":"19\/3\/2013 &#8211; CRITERIUM ITALIANO GIOVANI E SENIOR ECCO LA SQUADRA ALPI CENTRALI"},"content":{"rendered":"<p>Appuntamento sabato 23 e domenica 24 marzo a Sella Nevea per i campionati italiani Giovani e Senior di sci alpino. Una due giorni promossa dallo sci club Monte Canin di Udine in collaborazione con l\u2019Agenzia Regionale Promotur. La due giorni friulana \u00e8 aperta anche alle categorie Master<\/p>\n<p lang=\"it-IT\" align=\"JUSTIFY\">\u00a0<\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Arial, Arial, sans-serif\"><span style=\"font-size: large\">Questo il programma. Si inizia venerd\u00ec 22 marzo con le operazioni di accreditamento ed il sorteggio dei pettorali di gara. sabato 23, sulla pista Canin la prova di slalom speciale ed alle 14 la cerimonia di premiazione. Il giorno successivo sulla medesima pista la gara di slalom gigante ed alle 14 la cerimonia di premiazione.<\/span><\/span><\/p>\n<p align=\"JUSTIFY\">\u00a0<\/p>\n<p align=\"JUSTIFY\">\u00a0<\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Arial, Arial, sans-serif\"><span style=\"font-size: large\">In allegato la composizione della formazione maschile e femminile del Comitato FISI Alpi Centrali<\/span><\/span><\/p>\n<p align=\"JUSTIFY\">\u00a0<\/p>\n<p><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/wp-content\/uploads\/2013\/03\/AmmissioneCriterium_GS_F_1213.pdf\" target=\"_blank\" rel=\"noopener\"><\/p>\n<p align=\"JUSTIFY\">\u00a0Fomazione femminile<\/p>\n<p><\/a><\/p>\n<p align=\"JUSTIFY\">\u00a0<a href=\"https:\/\/www.fisialpicentrali.it\/cms\/wp-content\/uploads\/2013\/03\/AmmissioneCriterium_GS_M_1213.pdf\" target=\"_blank\" rel=\"noopener\">Formazione maschile<\/a><\/p>\n<p align=\"JUSTIFY\">\u00a0<\/p>\n<p align=\"JUSTIFY\">\u00a0<\/p>\n<p align=\"JUSTIFY\">\u00a0<\/p>\n<p align=\"JUSTIFY\">\u00a0<\/p>\n<p align=\"JUSTIFY\">\u00a0<\/p>\n<p align=\"JUSTIFY\">\u00a0<\/p>\n<p align=\"JUSTIFY\">\u00a0<\/p>\n<p align=\"RIGHT\"><span style=\"font-family: Arial, Arial, sans-serif\"><span style=\"font-size: medium\">Marco Cerottini<\/span><\/span><\/p>\n<p align=\"RIGHT\"><span style=\"font-family: Arial, Arial, sans-serif\"><span style=\"font-size: medium\">Ufficio stampa Comitato FISI Alpi Centrali<\/span><\/span><\/p>\n<p align=\"RIGHT\"><span style=\"font-family: Arial, Arial, sans-serif\"><span style=\"font-size: medium\">Tel.: 3475791302<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Appuntamento sabato 23 e domenica 24 marzo a Sella Nevea per i campionati italiani Giovani e Senior di sci alpino. Una due giorni promossa dallo sci club Monte Canin di Udine in collaborazione con l\u2019Agenzia Regionale Promotur. La due giorni friulana \u00e8 aperta anche alle categorie Master \u00a0 Questo il programma. Si inizia venerd\u00ec 22 marzo con le operazioni di&hellip;<\/p>\n","protected":false},"author":4,"featured_media":492911,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/495981"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=495981"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/495981\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/492911"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=495981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=495981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=495981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}