{"id":493003,"date":"2013-03-14T21:20:44","date_gmt":"2013-03-14T20:20:44","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=493003"},"modified":"2013-03-14T21:20:44","modified_gmt":"2013-03-14T20:20:44","slug":"493003","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2013\/03\/14\/493003\/","title":{"rendered":"14\/3\/2013 &#8211; TEMU\u2019: BARUFFALDI E VITTORI NEO CAMPIONI REGIONALI"},"content":{"rendered":"<p><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/493003\/podio-cr-all2\/\" rel=\"attachment wp-att-495234\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-495234\" alt=\"Podio cr all2\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/03\/Podio-cr-all2.jpg\" width=\"450\" height=\"300\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/03\/Podio-cr-all2.jpg 450w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/03\/Podio-cr-all2-300x200.jpg 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/a><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/493003\/podio-cr-allm2\/\" rel=\"attachment wp-att-495235\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-495235\" alt=\"podio cr allm2\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/03\/podio-cr-allm2.jpg\" width=\"450\" height=\"300\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/03\/podio-cr-allm2.jpg 450w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/03\/podio-cr-allm2-300x200.jpg 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/a>\u00a0<\/p>\n<p>Oggi a Tem\u00f9 prima giornata di gara per le categorie Allievi e Ragazzi maschile impegnate nei campionati regionali del Comitato FISI Alpi Centrali.<\/p>\n<p>&nbsp;<\/p>\n<p>Sulla pista Roccoloventura la prova di slalom gigante maschile, con la vittoria di Antonio Vittori dello sci club Altavalssasina. Al secondo posto Nicol\u00f2 Molteni dello sci club Lecco e terzo posto per Lorenzo Moschini dello sci club Collio. In campo femminile si impone Alessia Minazzi dello sci club san Domenico, mentre al secondo posto medaglia d\u2019argento per Angelica Rizzi dello Ski Team Valpalot. Chiude il podio Marika Mascherona dello sci club Bormio<\/p>\n<p><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/493003\/podio-cr-rag-f2\/\" rel=\"attachment wp-att-495237\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-495237\" alt=\"podio cr rag f2\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/03\/podio-cr-rag-f2.jpg\" width=\"450\" height=\"300\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/03\/podio-cr-rag-f2.jpg 450w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/03\/podio-cr-rag-f2-300x200.jpg 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/a><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/493003\/podio-cr-rag-m-sl2\/\" rel=\"attachment wp-att-495239\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-495239\" alt=\"podio cr rag m sl2\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/03\/podio-cr-rag-m-sl2.jpg\" width=\"450\" height=\"300\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/03\/podio-cr-rag-m-sl2.jpg 450w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/03\/podio-cr-rag-m-sl2-300x200.jpg 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/a>\u00a0<\/p>\n<p>Sulla pista Cadd\u00ec al Passo Tonale in scena lo slalom speciale categoria Ragazzi. Si impone il lecchese Davide Baruffaldi (SC Lecco) che ha regolato Matteo Pedroncelli (IAT Madesimo) ed Emanuele Radici dello sci club Radici Group. In campo femminile, invece, la medaglia d\u2019oro \u00e8 andata a Silvia Turla dello Ski Team Valpalot, argento per Carolina Pozzi (SC Bormio) e medaglia di bronzo per Angelica Feltre dello sci club Amici di Madesimo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Oggi a Tem\u00f9 prima giornata di gara per le categorie Allievi e Ragazzi maschile impegnate nei campionati regionali del Comitato FISI Alpi Centrali. &nbsp; Sulla pista Roccoloventura la prova di slalom gigante maschile, con la vittoria di Antonio Vittori dello sci club Altavalssasina. Al secondo posto Nicol\u00f2 Molteni dello sci club Lecco e terzo posto per Lorenzo Moschini dello&hellip;<\/p>\n","protected":false},"author":4,"featured_media":493004,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/493003"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=493003"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/493003\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/493004"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=493003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=493003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=493003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}