{"id":485902,"date":"2013-03-02T21:26:45","date_gmt":"2013-03-02T20:26:45","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=485902"},"modified":"2013-03-02T21:26:45","modified_gmt":"2013-03-02T20:26:45","slug":"232013-italiani-di-sci-alpino-la-lorini-che-brava","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2013\/03\/02\/232013-italiani-di-sci-alpino-la-lorini-che-brava\/","title":{"rendered":"2\/3\/2013 &#8211; ITALIANI DI SCI ALPINO: LA LORINI CHE BRAVA"},"content":{"rendered":"<p align=\"JUSTIFY\">\u00a0<a href=\"https:\/\/www.fisialpicentrali.it\/cms\/232013-italiani-di-sci-alpino-la-lorini-che-brava\/lorini2art\/\" rel=\"attachment wp-att-485907\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-485907\" alt=\"Lorini2^art\" src=\"https:\/\/www.fisialpicentrali.it\/cms\/wp-content\/uploads\/2013\/03\/Lorini2^art.jpg\" width=\"450\" height=\"315\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/03\/Lorini2^art.jpg 450w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/03\/Lorini2^art-300x210.jpg 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/a><\/p>\n<p><span style=\"font-size: medium\"><b>Giulia Lorini, sci club Medesimo<\/b>, conquista una bellissima e pesantissima <b>medaglia d\u2019argento nella prova di slalom speciale valida per i campionati italiani<\/b> che, per quanto riguarda il settore femminile, si sono conclusi oggi sulle nevi di <b>Tarvisio e di Sella Nevea<\/b>.<\/span><\/p>\n<p><span style=\"font-size: medium\">\u00a0<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: 'Times New Roman', serif;font-size: medium\"><span style=\"font-family: Arial, sans-serif\">La Lorini, partita con un pettorale decisamente sfavorevole (il numero 18) \u00e8 stata autrice di due manche superlative e solo 15 centesimi non hanno permesso all\u2019alfiere dello <\/span><span style=\"font-family: Arial, sans-serif\"><b>sci club Medesimo<\/b><\/span><span style=\"font-family: Arial, sans-serif\"> di conquistare la medaglia d\u2019oro. Nella prova fra i pali stretti odierna il <\/span><span style=\"font-family: Arial, sans-serif\"><b>Comitato FISI Alpi Centrali<\/b><\/span><span style=\"font-family: Arial, sans-serif\"> piazza altre <\/span><span style=\"font-family: Arial, sans-serif\"><b>2 atlete<\/b><\/span><span style=\"font-family: Arial, sans-serif\"> nei primi dieci posti della classifica assoluta. <\/span><span style=\"font-family: Arial, sans-serif\"><b>Ottava <\/b><\/span><span style=\"font-family: Arial, sans-serif\">piazza per<\/span><span style=\"font-family: Arial, sans-serif\"><b> Roberta Melesi <\/b><\/span><span style=\"font-family: Arial, sans-serif\">dello<\/span><span style=\"font-family: Arial, sans-serif\"><b> sci club Radici Group<\/b><\/span><span style=\"font-family: Arial, sans-serif\"> e <\/span><span style=\"font-family: Arial, sans-serif\"><b>decimo posto<\/b><\/span><span style=\"font-family: Arial, sans-serif\"> per <\/span><span style=\"font-family: Arial, sans-serif\"><b>Angelica Casartelli<\/b><\/span><span style=\"font-family: Arial, sans-serif\"> dello <\/span><span style=\"font-family: Arial, sans-serif\"><b>sci club Lecco<\/b><\/span><span style=\"font-family: Arial, sans-serif\">. Infine, da annotare, anche il <\/span><span style=\"font-family: Arial, sans-serif\"><b>13esimo post per Ymer Sola<\/b><\/span><span style=\"font-family: Arial, sans-serif\">, dello sci club Radici Group.<\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-size: medium\">\u00a0<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: 'Times New Roman', serif;font-size: medium\"><span style=\"font-family: Arial, sans-serif\">Peccato per <\/span><span style=\"font-family: Arial, sans-serif\"><b>Veronica Olivieri<\/b><\/span><span style=\"font-family: Arial, sans-serif\"> (<\/span><span style=\"font-family: Arial, sans-serif\"><b>Futur FISI<\/b><\/span><span style=\"font-family: Arial, sans-serif\">) che partita con il pettorale numero uno \u00e8 uscita subito dai giochi inforcando dopo poche porte nel corso della prima frazione di gara. Nella prima manche out anche <\/span><span style=\"font-family: Arial, sans-serif\"><b>Jole Galli<\/b><\/span><span style=\"font-family: Arial, sans-serif\"> (<\/span><span style=\"font-family: Arial, sans-serif\"><b>SC Livigno<\/b><\/span><span style=\"font-family: Arial, sans-serif\">). Nella seconda frazione di gara, invece, \u00e8 uscita <\/span><span style=\"font-family: Arial, sans-serif\"><b>Martina Nobis<\/b><\/span><span style=\"font-family: Arial, sans-serif\"> dello <\/span><span style=\"font-family: Arial, sans-serif\"><b>sci club Lecco<\/b><\/span><span style=\"font-family: Arial, sans-serif\">.<\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-size: medium\">\u00a0<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-size: medium\">\u201c<span style=\"font-family: 'Times New Roman', serif\"><span style=\"font-family: Arial, sans-serif\">Giulia Lorini \u00e8 stata perfetta sia nella prima sia nella seconda manche \u2013 commenta <\/span><span style=\"font-family: Arial, sans-serif\"><b>Elio Presazzi<\/b><\/span><span style=\"font-family: Arial, sans-serif\"> allenatore della formazione femminile del <\/span><span style=\"font-family: Arial, sans-serif\"><b>Comitato FISI Alpi Centrali<\/b><\/span><span style=\"font-family: Arial, sans-serif\"> di sci alpino \u2013 e sono molto contento della sua prova, cos\u00ec come quella delle altre ragazze. Come formazione delle Alpi Centrali, al termine di queste gare tricolori, portiamo a casa due medaglie d\u2019argento molto importanti\u201d.<\/span><\/span><\/span><\/p>\n<p align=\"RIGHT\"><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: medium\">Marco Cerottini<\/span><\/span><\/p>\n<p align=\"RIGHT\"><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: medium\">Ufficio stampa Comitato FISI Alpi Centrali<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Giulia Lorini, sci club Medesimo, conquista una bellissima e pesantissima medaglia d\u2019argento nella prova di slalom speciale valida per i campionati italiani che, per quanto riguarda il settore femminile, si sono conclusi oggi sulle nevi di Tarvisio e di Sella Nevea. \u00a0 La Lorini, partita con un pettorale decisamente sfavorevole (il numero 18) \u00e8 stata autrice di due manche&hellip;<\/p>\n","protected":false},"author":4,"featured_media":485905,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/485902"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=485902"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/485902\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/485905"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=485902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=485902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=485902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}