{"id":485583,"date":"2013-03-01T16:50:17","date_gmt":"2013-03-01T15:50:17","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=485583"},"modified":"2013-03-01T16:50:17","modified_gmt":"2013-03-01T15:50:17","slug":"132013-gigante-femminile-tricolore-bronzo-per-jole-galli","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2013\/03\/01\/132013-gigante-femminile-tricolore-bronzo-per-jole-galli\/","title":{"rendered":"1\/3\/2013 &#8211;   GIGANTE FEMMINILE TRICOLORE: BRONZO PER JOLE GALLI"},"content":{"rendered":"<p><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/132013-gigante-femminile-tricolore-bronzo-per-jole-galli\/bronzo_galli_010313art\/\" rel=\"attachment wp-att-485588\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-485588\" alt=\"Bronzo_Galli_010313art\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/03\/Bronzo_Galli_010313art.jpg\" width=\"450\" height=\"318\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/03\/Bronzo_Galli_010313art.jpg 450w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/03\/Bronzo_Galli_010313art-300x212.jpg 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/a>\u00a0<\/p>\n<p>Altra giornata ricca di emozioni per i colori del\u00a0Comitato FISI Alpi Centraliche nella prova \u201crosa\u201d di\u00a0slalom gigante\u00a0dei\u00a0campionati italiani di sci alpino\u00a0in corso di svolgimento a\u00a0Tarvisio e Sella Nevea\u00a0conquista una medaglia di\u00a0bronzo con Jole Galli\u00a0nella gara vinta da Arianna Stocco<\/p>\n<p>&nbsp;<\/p>\n<p>La Galli ha chiuso con il crono di 2:03:64 con 37 centesimi di gap dalla vincitrice. Oltre all\u2019importanza per aver conquistato la medaglia, questo bronzo per\u00a0Jole Galli\u00a0ha un peso specifico doppio. La sciatrice ha avuto costanza, dedizione ed ha lavorato a lungo per poter rientrare alla grande dopo, praticamente, due anni di stop forzato a causa di un grave infortunio.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cSono convinto che questa medaglia \u2013 ha commentato\u00a0Elio Presazziallenatore della formazione femminile dello sci alpino del\u00a0Comitato FISI Alpi Centrali\u00a0\u2013 assume un peso specifico molto importante per il morale della Galli che ha saputo interpretare al meglio questo tracciato, reso molto insidioso specie nella seconda manche, ma soprattutto \u00e8 una bella iniezione di fiducia per la restante parte di questa stagione per la nostra atleta\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Per quanto riguarda le altre ragazze di Elio Presazzi:\u00a0quarta piazza\u00a0perRoberta Melesi\u00a0che forse accusa un eccesso di stanchezza.\u00a0Decima piazzaper\u00a0Ymer Sola. Peccato, invece, per\u00a0Martina Nobis\u00a0e\u00a0Veronica Olivieri\u00a0che sono uscite nel corso della prima manche. La Olivieri, ora, punter\u00e0 tutto sullo slalom speciale in programma domani. Out nella seconda frazione di gara, invece,\u00a0Angelica Casartelli\u00a0e\u00a0Giulia Lorini.<\/p>\n<p>&nbsp;<\/p>\n<p>Marco Cerottini<\/p>\n<p>Ufficio stampa Comitato FISI Alpi Centrali<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Altra giornata ricca di emozioni per i colori del\u00a0Comitato FISI Alpi Centraliche nella prova \u201crosa\u201d di\u00a0slalom gigante\u00a0dei\u00a0campionati italiani di sci alpino\u00a0in corso di svolgimento a\u00a0Tarvisio e Sella Nevea\u00a0conquista una medaglia di\u00a0bronzo con Jole Galli\u00a0nella gara vinta da Arianna Stocco &nbsp; La Galli ha chiuso con il crono di 2:03:64 con 37 centesimi di gap dalla vincitrice. Oltre all\u2019importanza per&hellip;<\/p>\n","protected":false},"author":4,"featured_media":485579,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/485583"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=485583"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/485583\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/485579"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=485583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=485583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=485583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}