{"id":484910,"date":"2013-02-26T20:26:47","date_gmt":"2013-02-26T19:26:47","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=484910"},"modified":"2013-02-26T20:26:47","modified_gmt":"2013-02-26T19:26:47","slug":"2622013-notizie-dai-mondiali-jr-in-canada","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2013\/02\/26\/2622013-notizie-dai-mondiali-jr-in-canada\/","title":{"rendered":"26\/2\/2013 &#8211; Notizie dai Mondiali Jr in Canada"},"content":{"rendered":"<p><strong>Mondiali jr. di sci alpino femminile: alla francese Piot il titolo della discesa. Ottimo sesto posto di Marta Bassino<\/strong><\/p>\n<p>E&#8217; della francese Jennifer Piot il titolo junior della discesa ai Mondialini del Quebec. La Piot ha battuto l&#8217;austriaca Stephanie Venier per soli 4 centesimi, mentre il bronzo \u00e8 andato all&#8217;altra francese Romane Miradoli, staccata di 24 centesimi. Ottima prova dell&#8217;azzurra Marta Bassino sesta a 67 centesimi dalla vincitrice. Buona anche la gara di Karoline Pichler 17\/a, mentre \u00e8 23\/a Ida Giardini e 42\/a si piazza Alessia Medetti.<\/p>\n<p><strong>Mondiali jr. di sci alpino maschile: l&#8217;ultimo titolo va a Manuel Feller nello slalom. 10\/o Zingerle<\/strong><\/p>\n<p>Manuel Feller porta all&#8217;Austria l&#8217;ultima medaglia d&#8217;oro dei Mondiali jr. di sci alpino che si sono svolti nel Quebec. Sulla pista di Mont St. Anne, l&#8217;austriaco ha condotto la prima manche e ha controllato nella seconda concludendo con il tempo di 1&#8217;59&#8243;40. La medaglia d&#8217;argento \u00e8 andata allo svizzero Ramon Zenhaeusern, risalito dalla terza posizione di met\u00e0 gara, mentre il bronzo va al finlandese Santeri Paloniemi, capace di risalire dalla quarta. Un vero perccato per l&#8217;azzurro Giordano Ronci, settimo a met\u00e0 gara a 66 centesimi dal bronzo, ma uscito nella seconda manche. Il migliore dei nostri \u00e8 ancora Alex Zingerle che dopo l&#8217;argento del gigante porta a casa il decimo posto fra i rapid gates. Zingerle \u00e8 anche l&#8217;unico piazzato degli azzurri, visto che tutti gli altri iscritti non hanno terminato la gara. Erano al via, oltre a Zingerle e Ronci, Pietro Franceschetti, Emanuele Buzzi, Fabian Bacher e Stefano Baruffaldi.<br \/>L&#8217;Italia chiude quindi il Mondiale con una medaglia complessiva: proprio l&#8217;argento di Zingerle nel gigante.<\/p>\n<p>Fonte Fisi.org<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mondiali jr. di sci alpino femminile: alla francese Piot il titolo della discesa. Ottimo sesto posto di Marta Bassino E&#8217; della francese Jennifer Piot il titolo junior della discesa ai Mondialini del Quebec. La Piot ha battuto l&#8217;austriaca Stephanie Venier per soli 4 centesimi, mentre il bronzo \u00e8 andato all&#8217;altra francese Romane Miradoli, staccata di 24 centesimi. Ottima prova dell&#8217;azzurra&hellip;<\/p>\n","protected":false},"author":4,"featured_media":481764,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/484910"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=484910"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/484910\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/481764"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=484910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=484910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=484910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}