{"id":481521,"date":"2013-02-21T19:00:33","date_gmt":"2013-02-21T18:00:33","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=481521"},"modified":"2013-02-21T19:00:33","modified_gmt":"2013-02-21T18:00:33","slug":"2122013-eyowf-settima-piazza-per-tommaso-sala-in-slalom","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2013\/02\/21\/2122013-eyowf-settima-piazza-per-tommaso-sala-in-slalom\/","title":{"rendered":"21\/2\/2013 &#8211; EYOWF: SETTIMA PIAZZA PER TOMMASO SALA IN SLALOM"},"content":{"rendered":"<p align=\"JUSTIFY\"><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">Nella prova fra i pali stretti di <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Brasov<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">, in Romania dove \u00e8 in corso di svolgimento <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>l\u2019European Youth Olympic Winter Festival<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">, settima piazza per il <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>lecchese Tommaso Sala<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"> secondo miglior azzurro in gara quest\u2019oggi nella prova vinta dallo sloveno Stefan Hadalin con il tempo di 1:31:69. Sala ha fatto fermare il cronometro con il tempo di 1:34:68. Miglior azzurro \u00e8 stato Hannes Zingerle che ha chiuso in quinta posizione. Out nella seconda manche Davide Da Villa e Federico Liberatore.<\/span><\/span><\/p>\n<p align=\"JUSTIFY\">\u00a0<\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">Male invece, Emil Bormetti dello sci club Livigno nella prova maschile sprint di biathlon sulla distanza dei 7.5 chilometri. L\u2019atleta della formazione del Comitato FISI Alpi Centrali ha chiuso in 69esima posizione. Miglior azzurro in gara Andrea Baretto che ha chiuso 18esimo. <\/span><\/span><\/p>\n<p align=\"JUSTIFY\">\u00a0<\/p>\n<p align=\"JUSTIFY\">\u00a0<\/p>\n<p align=\"RIGHT\"><span style=\"font-family: Arial, sans-serif\">Marco Cerottini<\/span><\/p>\n<p align=\"RIGHT\"><span style=\"font-family: Arial, sans-serif\">Ufficio stampa Comitato FISI Alpi Centrali<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nella prova fra i pali stretti di Brasov, in Romania dove \u00e8 in corso di svolgimento l\u2019European Youth Olympic Winter Festival, settima piazza per il lecchese Tommaso Sala secondo miglior azzurro in gara quest\u2019oggi nella prova vinta dallo sloveno Stefan Hadalin con il tempo di 1:31:69. Sala ha fatto fermare il cronometro con il tempo di 1:34:68. Miglior azzurro \u00e8&hellip;<\/p>\n","protected":false},"author":4,"featured_media":481522,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/481521"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=481521"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/481521\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/481522"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=481521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=481521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=481521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}