{"id":475969,"date":"2013-02-08T18:06:30","date_gmt":"2013-02-08T17:06:30","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=475969"},"modified":"2013-02-08T18:06:30","modified_gmt":"2013-02-08T17:06:30","slug":"22013-a-la-thuille-cerini-e-bosca-super","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2013\/02\/08\/22013-a-la-thuille-cerini-e-bosca-super\/","title":{"rendered":"8\/2\/2013-  A LA THUILLE: CERINI E BOSCA SUPER!"},"content":{"rendered":"<p align=\"JUSTIFY\">\u00a0<\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: 'Times New Roman', serif\"><span style=\"font-size: medium\"><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">Super gigante di <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Coppa Europa<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"> sulle nevi della <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Valle d\u2019Aosta<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"> quest\u2019oggi. Ottime cose da parte sia di <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Norman Cerini<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"> (SC Formazza) sia da <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Carlo Beretta<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"> (CS Madesimo) della formazione dello sci alpino del <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Comitato FISI Alpi Centrali<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">. Il primo \u00e8 risultato essere il <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>secondo miglior azzurro <\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">dietro solo a Guglielmo Bosca. Beretta, invece, \u00e8 il <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>terzo miglior azzurro<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">. Cerini chiude la sua performance con il crono di 1\u201913\u201d31 con il 46esimo tempo assoluto. Beretta, invece, ha fatto fermare il crono sul tempo di 1\u2019:13\u201d:36.<\/span><\/span><\/span><\/span><\/p>\n<p align=\"JUSTIFY\">\u00a0<\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">Per la cronaca. La gara \u00e8 stata vinta dal norvegese Aamodt Aleksander Kilde che ha chiuso con il tempo di 1:09:54. Dietro di lui l\u2019austriaco Vicent Krichmayr con il tempo di 1:09:60. Terzo posto per il tedesco Josef Ferstl con il tempo di 1:10:71. Miglior azzurro, nella classifica assoluto, Silvano Varettoni che conclude quinto con il tempo di 1:10:80<\/span><\/span><\/p>\n<p align=\"JUSTIFY\">\u00a0<\/p>\n<p>Per quanto riguarda gli altri appuntamenti del circuito Gran Prix Italia di sci alpino maschile. Le prove in programma all\u2019Abetone luned\u00ec e marted\u00ec sono state spostate a gioved\u00ec e venerd\u00ec sempre sulle nevi dell\u2019Appennino emiliano.<\/p>\n<p align=\"JUSTIFY\">\u00a0<\/p>\n<p align=\"JUSTIFY\">\u00a0<\/p>\n<p align=\"JUSTIFY\">\u00a0<\/p>\n<p align=\"JUSTIFY\">\u00a0<\/p>\n<p align=\"JUSTIFY\">\u00a0<\/p>\n<p align=\"LEFT\"><span style=\"color: #000000\">\u00a0<\/span><\/p>\n<p align=\"JUSTIFY\">\u00a0<\/p>\n<p align=\"RIGHT\"><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: medium\">Marco Cerottini<\/span><\/span><\/p>\n<p align=\"RIGHT\"><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: medium\">Ufficio stampa Comitato FISI Alpi Centrali<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Super gigante di Coppa Europa sulle nevi della Valle d\u2019Aosta quest\u2019oggi. Ottime cose da parte sia di Norman Cerini (SC Formazza) sia da Carlo Beretta (CS Madesimo) della formazione dello sci alpino del Comitato FISI Alpi Centrali. Il primo \u00e8 risultato essere il secondo miglior azzurro dietro solo a Guglielmo Bosca. Beretta, invece, \u00e8 il terzo miglior azzurro. Cerini&hellip;<\/p>\n","protected":false},"author":4,"featured_media":475971,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/475969"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=475969"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/475969\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/475971"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=475969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=475969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=475969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}