{"id":472449,"date":"2013-02-01T15:46:43","date_gmt":"2013-02-01T14:46:43","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=472449"},"modified":"2013-02-01T15:46:43","modified_gmt":"2013-02-01T14:46:43","slug":"122013-i-big-dello-sci-alpino-al-monte-pora","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2013\/02\/01\/122013-i-big-dello-sci-alpino-al-monte-pora\/","title":{"rendered":"1\/2\/2013 &#8211; I Big  dello Sci Alpino Mondiale al Monte Pora"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Sabato e domenica la\u00a0Coppa Europa\u00a0di sci alpino sbarca in Lombardia e pi\u00f9 precisamente sulle nevi del Monte Pora. L\u2019evento \u00e8 organizzato dallo\u00a0Sci Club Radici Group,\u00a0e vedr\u00e0 al via alcuni dei migliori atleti, sia professionisti che juniores, del panorama italiano e internazionale.<\/p>\n<p>&nbsp;<\/p>\n<p>Sabato 2\u00a0febbraio andr\u00e0 in scena lo\u00a0Slalom Gigante\u00a0con il Trofeo assoluto IVS Italia e Trofeo Juniores RIBES &#8211; RE Valuta,\u00a0mentre\u00a0domenica 3\u00a0si disputer\u00e0 lo\u00a0Slalom Speciale\u00a0con il\u00a0Trofeo assoluto Immobiliare Percassi e Trofeo Juniores RIBES \u2013 RE Valuta.<\/p>\n<p>&nbsp;<\/p>\n<p>Tra gli iscritti alla due giorni di gare, nomi di primissimo piano comeMassimiliano Blardone\u00a0e\u00a0Roberto Nani,\u00a0tutti e due atleti cresciuti sportivamente parlando fra le fila del\u00a0Comitato FISI Alpi Centrali,\u00a0che dopo la Coppa Europa\u00a0saranno tra i protagonisti agli imminenti Mondiali di sci alpino in programma a\u00a0Schladming\u00a0in Austria dal 5 al 17 febbraio. La competizione dei pali larghi sar\u00e0 dunque un test importante per gli azzurri in vista delle competizioni iridate. Ma sulle nevi lombarde sono attesi anche: l\u2019austriaco\u00a0Marcel Mathis, il giapponese\u00a0Akira Sasaki, gli svedesi\u00a0Mattias Hargin\u00a0e\u00a0Jon Olsson. E ancora, gli svizzeri\u00a0Marc Berthod,\u00a0Markus Vogel\u00a0eMarc Gini\u00a0e il francese\u00a0Maxime Tissot.<\/p>\n<p>&nbsp;<\/p>\n<p>La due giorni di competizioni al Monte Pora sar\u00e0 l\u2019occasione per ricordare l\u2019immenso Fausto Radici uno degli alfieri della valanga azzurra degli anni settanta che domin\u00f2 le specialit\u00e0 tecniche dello sci alpino nonostante fosse privo di vista da un occhio<\/p>\n<p>Marco Cerottini<\/p>\n<p>Ufficio stampa Comitato FISI Alpi Centrali<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Sabato e domenica la\u00a0Coppa Europa\u00a0di sci alpino sbarca in Lombardia e pi\u00f9 precisamente sulle nevi del Monte Pora. L\u2019evento \u00e8 organizzato dallo\u00a0Sci Club Radici Group,\u00a0e vedr\u00e0 al via alcuni dei migliori atleti, sia professionisti che juniores, del panorama italiano e internazionale. &nbsp; Sabato 2\u00a0febbraio andr\u00e0 in scena lo\u00a0Slalom Gigante\u00a0con il Trofeo assoluto IVS Italia e Trofeo Juniores RIBES &#8211;&hellip;<\/p>\n","protected":false},"author":4,"featured_media":472451,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/472449"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=472449"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/472449\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/472451"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=472449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=472449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=472449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}