{"id":444378,"date":"2013-01-25T18:16:05","date_gmt":"2013-01-25T17:16:05","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=444378"},"modified":"2013-01-25T18:16:05","modified_gmt":"2013-01-25T17:16:05","slug":"2512012-super-ida-a-san-candidato-e-medaglia-dargento","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2013\/01\/25\/2512012-super-ida-a-san-candidato-e-medaglia-dargento\/","title":{"rendered":"25\/1\/2013 &#8211;  SUPER IDA. A SAN CANDIDO E\u2019 MEDAGLIA D\u2019ARGENTO"},"content":{"rendered":"<p align=\"JUSTIFY\">\u00a0<\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Ida Giardini<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">, atleta del gruppo FUTUR FISI ed alfiere della formazione femminile di sci alpino del <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Comitato Alpi Centrali<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">, conquista una straordinaria <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>seconda piazza<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">, nello slalom gigante FIS di San Candido valido come prova del circuito <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Gran Prix Italia<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">, dietro solo alla tedesca Mren Wiesler. La teutonica ha rifilato 55 centesimi alla Giardini.<\/span><\/span><\/p>\n<p align=\"JUSTIFY\">\u00a0<\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/2512012-super-ida-a-san-candidato-e-medaglia-dargento\/roberta-melesi-e-tiziana-sala\/\" rel=\"attachment wp-att-444405\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-444405\" alt=\"Roberta Melesi e Tiziana Sala\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/01\/Roberta-Melesi-e-Tiziana-Sala.jpg\" width=\"400\" height=\"353\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/01\/Roberta-Melesi-e-Tiziana-Sala.jpg 400w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/01\/Roberta-Melesi-e-Tiziana-Sala-300x265.jpg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a>Ma la giornata di San Candido fa segnare la super performance di <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Tiziana Sala<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">. L\u2019atleta dello sci club Radici Group, partita con il pettorale numero uno ha chiuso la prima manche in trentesima posizione. Ma l\u2019atleta della formazione \u201crosa\u201d del <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Comitato FISI Alpi C<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">entrali non si \u00e8 data per vinta e con una seconda manche superlativa \u00e8 riuscita a compiere una vera e propria rimonta ed a chiudere in <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>14esima posizione assoluta e settima<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"> nella categoria Giovani con il tempo di 2:07:08. Bene anche la compagna di squadra della Sala, <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Roberta Melesi<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"> che centra la <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>settima posizione giovani ed l\u2019undicesima piazza assoluta<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"> chiudendo con il crono di 2:06:57. Nelle prime trenta anche: <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Roberta Midali <\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">(Futur FISI), <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Veronica Olivieri <\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">(FUTUR FISI) e <\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"><b>Jole Galli<\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\"> (SC Livigno) rispettivamente 21esima, 27esima e 29esima.<\/span><\/span><\/p>\n<p align=\"JUSTIFY\">\u00a0<\/p>\n<p align=\"JUSTIFY\">\u201c<span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: large\">In slalom gigante siamo davvero in forma \u2013 commenta un raggiante Elio Presazzi allenatore della formazione femminile di sci alpino del Comitato FISI Alpi Centrali \u2013 e sono contento della performance di tutte le mie ragazze. Quella di oggi \u00e8 una bella iniezione di fiducia per la stagione\u201d. Ora le ragazze di Presazzi avranno qualche giorno di riposo. Poi tutti in pista per una nuova tappa del circuito Gran Prix Italia in programma mercoled\u00ec e gioved\u00ec prossimi a Cavalese sede di uno slalom gigante e di uno slalom speciale.<\/span><\/span><\/p>\n<p align=\"RIGHT\"><span style=\"font-family: Arial, sans-serif\">Marco Cerottini<\/span><\/p>\n<p align=\"RIGHT\"><span style=\"font-family: Arial, sans-serif\">Ufficio stampa Comitato FISI Alpi Central<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Ida Giardini, atleta del gruppo FUTUR FISI ed alfiere della formazione femminile di sci alpino del Comitato Alpi Centrali, conquista una straordinaria seconda piazza, nello slalom gigante FIS di San Candido valido come prova del circuito Gran Prix Italia, dietro solo alla tedesca Mren Wiesler. La teutonica ha rifilato 55 centesimi alla Giardini. \u00a0 Ma la giornata di San&hellip;<\/p>\n","protected":false},"author":4,"featured_media":444384,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/444378"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=444378"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/444378\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/444384"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=444378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=444378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=444378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}